{"id":22256,"date":"2026-01-28T08:11:32","date_gmt":"2026-01-28T16:11:32","guid":{"rendered":"https:\/\/drugpolicy.ca\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/"},"modified":"2026-02-02T10:41:33","modified_gmt":"2026-02-02T18:41:33","slug":"complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires","status":"publish","type":"post","link":"https:\/\/www.drugpolicy.ca\/fr\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/","title":{"rendered":"Complicit\u00e9 du Canada avec les frappes militaires ill\u00e9gales des \u00c9tats-Unis : Quand la politique de sant\u00e9 publique en mati\u00e8re de drogues rencontre les ex\u00e9cutions extrajudiciaires"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Depuis le 2 septembre 2025, l&#8217;arm\u00e9e am\u00e9ricaine a tu\u00e9 au moins 57 civils dans les eaux internationales, lors de frappes que le droit international et les autorit\u00e9s charg\u00e9es des droits de l&#8217;homme ont condamn\u00e9es comme \u00e9tant ill\u00e9gales.<\/strong><sup data-fn=\"0ff9e067-370c-4ee1-a209-672bf18d1778\" class=\"fn\"><a id=\"0ff9e067-370c-4ee1-a209-672bf18d1778-link\" href=\"#0ff9e067-370c-4ee1-a209-672bf18d1778\">1<\/a><\/sup> Des preuves de plus en plus nombreuses d\u00e9montrent l&#8217;implication importante du Canada dans ces op\u00e9rations militaires men\u00e9es par les \u00c9tats-Unis.<sup data-fn=\"6024ab37-7e94-400d-b291-781afa57f224\" class=\"fn\"><a id=\"6024ab37-7e94-400d-b291-781afa57f224-link\" href=\"#6024ab37-7e94-400d-b291-781afa57f224\">2<\/a><\/sup> <sup data-fn=\"48564a98-e338-42eb-94db-aeecdc82fbde\" class=\"fn\"><a id=\"48564a98-e338-42eb-94db-aeecdc82fbde-link\" href=\"#48564a98-e338-42eb-94db-aeecdc82fbde\">3<\/a><\/sup> <\/p>\n\n<p class=\"wp-block-paragraph\">\u00c0 la base, la politique prohibitionniste en mati\u00e8re de drogues est de plus en plus discr\u00e9dit\u00e9e, car elle ne parvient pas \u00e0 mettre un terme \u00e0 la consommation de drogues et r\u00e9ussit \u00e0 engendrer des dommages et des souffrances. Elle sape \u00e0 la fois les droits de l&#8217;homme et les r\u00e9ponses efficaces en mati\u00e8re de sant\u00e9 publique, \u00e0 l&#8217;int\u00e9rieur et \u00e0 l&#8217;ext\u00e9rieur du pays.<sup data-fn=\"0be014e6-9bf1-482b-848b-f1e91c845611\" class=\"fn\"><a id=\"0be014e6-9bf1-482b-848b-f1e91c845611-link\" href=\"#0be014e6-9bf1-482b-848b-f1e91c845611\">4<\/a><\/sup> Au lieu d&#8217;endiguer le flux de drogues non r\u00e9glement\u00e9es, la prohibition a pouss\u00e9 la production et le commerce de drogues dans la clandestinit\u00e9, renforc\u00e9 le crime organis\u00e9, port\u00e9 un pr\u00e9judice disproportionn\u00e9 \u00e0 des communaut\u00e9s d\u00e9j\u00e0 marginalis\u00e9es, acc\u00e9l\u00e9r\u00e9 la d\u00e9gradation de l&#8217;environnement et contribu\u00e9 \u00e0 l&#8217;instabilit\u00e9, \u00e0 la violence et aux violations des droits de l&#8217;homme \u00e0 l&#8217;\u00e9tranger, tout en alimentant une crise de la drogue toxique non r\u00e9glement\u00e9e dans le pays.<sup data-fn=\"5fe209ac-9306-4fa2-9245-effc1cd2fd44\" class=\"fn\"><a id=\"5fe209ac-9306-4fa2-9245-effc1cd2fd44-link\" href=\"#5fe209ac-9306-4fa2-9245-effc1cd2fd44\">5<\/a><\/sup><sup data-fn=\"d7118664-cd74-4bde-af50-f3199e56e258\" class=\"fn\"><a id=\"d7118664-cd74-4bde-af50-f3199e56e258-link\" href=\"#d7118664-cd74-4bde-af50-f3199e56e258\">6<\/a><\/sup><sup data-fn=\"91a6d1b9-3e54-4347-a94b-5fbf65b15389\" class=\"fn\"><a id=\"91a6d1b9-3e54-4347-a94b-5fbf65b15389-link\" href=\"#91a6d1b9-3e54-4347-a94b-5fbf65b15389\">7<\/a><\/sup><sup data-fn=\"a45e03bb-d460-43be-8b5c-a9e134eae88c\" class=\"fn\"><a id=\"a45e03bb-d460-43be-8b5c-a9e134eae88c-link\" href=\"#a45e03bb-d460-43be-8b5c-a9e134eae88c\">8<\/a><\/sup>  <\/p>\n\n<p class=\"wp-block-paragraph\">La <strong>campagne d&#8217;ex\u00e9cutions extrajudiciaires des \u00c9tats-Unis est une escalade dangereuse de la politique prohibitionniste<\/strong>, et en s&#8217;alignant et en y participant, le Canada abandonne ses valeurs d\u00e9clar\u00e9es et met en p\u00e9ril sa cr\u00e9dibilit\u00e9 internationale. Il n&#8217;y a rien \u00e0 gagner \u00e0 tenter d&#8217;apaiser l&#8217;actuel pr\u00e9sident am\u00e9ricain : La d\u00e9f\u00e9rence du Canada \u00e0 l&#8217;\u00e9gard des caprices du pr\u00e9sident Trump et sa complicit\u00e9 continue dans ces attaques ill\u00e9gales ne feront que causer du tort.   <\/p>\n\n<p class=\"wp-block-paragraph\">Passez \u00e0 l&#8217;<strong>action : <\/strong>exigez de nos dirigeants \u00e9lus qu&#8217;ils rendent des comptes. Exhortez votre d\u00e9put\u00e9 \u00e0   <\/p>\n\n<ul class=\"wp-block-list\">\n<li>supprimer l&#8217;\u00e9chappatoire de l&#8217;exportation d&#8217;armes<\/li>\n\n\n\n<li>soutenir le projet de loi C-233, et  <\/li>\n\n\n\n<li>suspendre le r\u00f4le du Canada dans l&#8217;op\u00e9ration CARIBBE.  <\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">La situation  <\/h2>\n\n<p class=\"wp-block-paragraph\">Le 2 septembre 2025, le pr\u00e9sident am\u00e9ricain Donald Trump a annonc\u00e9 que l&#8217;arm\u00e9e am\u00e9ricaine avait men\u00e9 une frappe a\u00e9rienne sur un navire dans les Cara\u00efbes, affirmant que le bateau \u00e9tait utilis\u00e9 par le cartel Tren de Aragua pour faire passer de la drogue depuis le Venezuela.<sup data-fn=\"00ea1fe4-1771-403f-8d4a-b9a14be0c03f\" class=\"fn\"><a id=\"00ea1fe4-1771-403f-8d4a-b9a14be0c03f-link\" href=\"#00ea1fe4-1771-403f-8d4a-b9a14be0c03f\">9<\/a><\/sup> Depuis lors, au moins neuf autres frappes ont vis\u00e9 des bateaux civils dans les eaux internationales, tant dans les Cara\u00efbes que dans le Pacifique Est. <strong>Le nombre de morts s&#8217;\u00e9l\u00e8ve d\u00e9sormais \u00e0 57 personnes au minimum.<\/strong> L&#8217;administration Trump n&#8217;a fourni aucune preuve \u00e0 l&#8217;appui de ses all\u00e9gations de trafic de drogue.<sup data-fn=\"fbf04cbf-01e3-45cc-b434-50a41c30a183\" class=\"fn\"><a id=\"fbf04cbf-01e3-45cc-b434-50a41c30a183-link\" href=\"#fbf04cbf-01e3-45cc-b434-50a41c30a183\">10<\/a><\/sup><sup data-fn=\"ab3c3897-772b-4c8b-8259-cef57adbc3fd\" class=\"fn\"><a id=\"ab3c3897-772b-4c8b-8259-cef57adbc3fd-link\" href=\"#ab3c3897-772b-4c8b-8259-cef57adbc3fd\">11<\/a><\/sup><sup data-fn=\"b135c1a8-6963-4124-9e2e-a781ef95edc9\" class=\"fn\"><a id=\"b135c1a8-6963-4124-9e2e-a781ef95edc9-link\" href=\"#b135c1a8-6963-4124-9e2e-a781ef95edc9\">12<\/a><\/sup> <\/p>\n\n<p class=\"wp-block-paragraph\">Alors que l&#8217;administration Trump pr\u00e9sente ces attaques comme faisant partie d&#8217;une campagne militaire contre le trafic de drogue, Human Rights Watch les a cat\u00e9goriquement qualifi\u00e9es d&#8217;<strong>ex\u00e9cutions extrajudiciaires en violation du droit international<\/strong> et du Pacte international relatif aux droits civils et politiques (PIDCP).<sup data-fn=\"27a6594d-e23d-4eba-95bd-d186909c1384\" class=\"fn\"><a id=\"27a6594d-e23d-4eba-95bd-d186909c1384-link\" href=\"#27a6594d-e23d-4eba-95bd-d186909c1384\">13<\/a><\/sup> Les experts notent que la justification fragile de Trump pourrait ne pas concerner la drogue du tout, mais plut\u00f4t servir de couverture \u00e0 l&#8217;ing\u00e9rence politique et au changement de r\u00e9gime au Venezuela.<sup data-fn=\"bc1c9f36-57d2-46b9-9110-2c0deabbeae1\" class=\"fn\"><a id=\"bc1c9f36-57d2-46b9-9110-2c0deabbeae1-link\" href=\"#bc1c9f36-57d2-46b9-9110-2c0deabbeae1\">14<\/a><\/sup> <\/p>\n\n<p class=\"wp-block-paragraph\">Pour comprendre pourquoi ces frappes sont ill\u00e9gales, il est important de savoir que, selon les experts juridiques, cette situation ne constitue pas un usage l\u00e9gal de la force militaire en vertu du droit international.<sup data-fn=\"ddb96e48-4747-4b21-95b3-7a6eead53ac4\" class=\"fn\"><a id=\"ddb96e48-4747-4b21-95b3-7a6eead53ac4-link\" href=\"#ddb96e48-4747-4b21-95b3-7a6eead53ac4\">15<\/a><\/sup> Il n&#8217;existe pas de conflit arm\u00e9 entre les \u00c9tats-Unis et les \u00c9tats cit\u00e9s par Trump, comme la Colombie ou le Venezuela, ni entre les \u00c9tats-Unis et les groupes criminels pr\u00e9sum\u00e9s impliqu\u00e9s. Le recours \u00e0 la force meurtri\u00e8re contre des civils en mer constitue une violation du droit \u00e0 la vie en vertu de l&#8217;article 6 du Pacte international relatif aux droits civils et politiques. <sup data-fn=\"f90f23e1-d5f2-4f87-a4ea-e80afc319880\" class=\"fn\"><a id=\"f90f23e1-d5f2-4f87-a4ea-e80afc319880-link\" href=\"#f90f23e1-d5f2-4f87-a4ea-e80afc319880\">16<\/a><\/sup>  <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Ces frappes constituent un recours ill\u00e9gal \u00e0 la force militaire ciblant des civils dans les eaux internationales, sans proc\u00e9dure r\u00e9guli\u00e8re ni contr\u00f4le judiciaire.<\/strong> Selon le droit des droits de l&#8217;homme, &#8220;les responsables de l&#8217;application de la loi, y compris le personnel militaire, doivent chercher \u00e0 minimiser les blessures et \u00e0 pr\u00e9server la vie humaine. Ils ne peuvent recourir \u00e0 la force meurtri\u00e8re que lorsque cela est strictement in\u00e9vitable pour se prot\u00e9ger contre une menace imminente de mort ou de blessure grave&#8221;.<sup data-fn=\"a01fb4b5-ea82-4050-875d-43cb8bf9a7ab\" class=\"fn\"><a id=\"a01fb4b5-ea82-4050-875d-43cb8bf9a7ab-link\" href=\"#a01fb4b5-ea82-4050-875d-43cb8bf9a7ab\">17<\/a><\/sup> En vertu du droit international et du droit canadien, lorsqu&#8217;une personne est accus\u00e9e d&#8217;avoir enfreint la loi, elle a le droit d&#8217;\u00eatre trait\u00e9e conform\u00e9ment \u00e0 ce que l&#8217;on appelle au Canada les principes de justice fondamentale et, dans certaines juridictions, les garanties d&#8217;une proc\u00e9dure r\u00e9guli\u00e8re. Cela inclut des protections de base telles que la pr\u00e9somption d&#8217;innocence, la confrontation des preuves dans le cadre d&#8217;un proc\u00e8s \u00e9quitable et la possibilit\u00e9 de faire appel.    <\/p>\n\n<p class=\"wp-block-paragraph\">L&#8217;Union am\u00e9ricaine pour les libert\u00e9s civiles a d\u00e9clar\u00e9 sans ambages : &#8220;Les frappes de bateaux de Trump tuent des civils potentiellement innocents : &#8220;Les frappes de bateaux de Trump tuent des civils potentiellement innocents. Il faut y mettre un terme&#8221;.<sup data-fn=\"225719cf-d3ab-403d-8bd9-f0b77c3876fa\" class=\"fn\"><a id=\"225719cf-d3ab-403d-8bd9-f0b77c3876fa-link\" href=\"#225719cf-d3ab-403d-8bd9-f0b77c3876fa\">18<\/a><\/sup><\/p>\n\n<h2 class=\"wp-block-heading\">L&#8217;implication du Canada  <\/h2>\n\n<p class=\"wp-block-paragraph\"><strong>Les preuves de la complicit\u00e9 du Canada dans les frappes ill\u00e9gales des \u00c9tats-Unis s&#8217;accumulent. Le Canada participe \u00e0 l&#8217;op\u00e9ration CARIBBE <\/strong>d\u00e9crit par le minist\u00e8re de la D\u00e9fense nationale comme &#8220;la contribution du Canada aux op\u00e9rations renforc\u00e9es de lutte contre les stup\u00e9fiants men\u00e9es par les \u00c9tats-Unis dans la mer des Cara\u00efbes et dans l&#8217;est de l&#8217;oc\u00e9an Pacifique&#8221;.<sup data-fn=\"27518e5d-b427-48b2-839f-0f020b5492fe\" class=\"fn\"><a id=\"27518e5d-b427-48b2-839f-0f020b5492fe-link\" href=\"#27518e5d-b427-48b2-839f-0f020b5492fe\">19<\/a><\/sup> Dans le cadre de CARIBBE, qui a d\u00e9but\u00e9 en 2006 et s&#8217;est \u00e9largi gr\u00e2ce \u00e0 un protocole d&#8217;accord conclu en 2010, les navires et les a\u00e9ronefs des Forces arm\u00e9es canadiennes sont d\u00e9ploy\u00e9s pour fournir des renseignements, de la surveillance, un soutien logistique et des \u00e9quipements qui permettent aux op\u00e9rations militaires am\u00e9ricaines de se d\u00e9rouler.  <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Le co\u00fbt ? Plus de 11 millions de dollars par an au cours des derniers exercices. <\/strong><sup data-fn=\"9efec4f6-756f-4eae-99f3-d25c211f944c\" class=\"fn\"><a id=\"9efec4f6-756f-4eae-99f3-d25c211f944c-link\" href=\"#9efec4f6-756f-4eae-99f3-d25c211f944c\">20<\/a><\/sup> <\/p>\n\n<p class=\"wp-block-paragraph\">Bien que le minist\u00e8re canadien de la d\u00e9fense nationale insiste sur le fait que ses activit\u00e9s sont &#8220;s\u00e9par\u00e9es et distinctes&#8221; des frappes a\u00e9riennes am\u00e9ricaines, de telles distinctions n&#8217;ont aucun sens en l&#8217;absence de contr\u00f4le ind\u00e9pendant. Les faits montrent que la participation du Canada fournit l&#8217;infrastructure de surveillance qui rend ces frappes possibles.   <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Plus accablant encore, la<\/strong> <strong>technologie canadienne a \u00e9t\u00e9 directement li\u00e9e aux frappes.<\/strong> Selon des recherches approfondies men\u00e9es par Project Ploughshares et v\u00e9rifi\u00e9es de mani\u00e8re ind\u00e9pendante par CBC, des capteurs fabriqu\u00e9s au Canada ont probablement aid\u00e9 \u00e0 identifier les cibles des r\u00e9centes frappes am\u00e9ricaines pr\u00e8s du Venezuela.<sup data-fn=\"80d4825b-b73e-4dcd-bc57-77fe3fe64376\" class=\"fn\"><a id=\"80d4825b-b73e-4dcd-bc57-77fe3fe64376-link\" href=\"#80d4825b-b73e-4dcd-bc57-77fe3fe64376\">21<\/a><\/sup><sup data-fn=\"845f0db9-1c4c-4677-988c-669a87423ba1\" class=\"fn\"><a id=\"845f0db9-1c4c-4677-988c-669a87423ba1-link\" href=\"#845f0db9-1c4c-4677-988c-669a87423ba1\">22<\/a><\/sup> En fournissant un soutien logistique, des renseignements, une surveillance et des \u00e9quipements, le Canada est complice de ces ex\u00e9cutions extrajudiciaires, que ce soit ou non un citoyen canadien qui tire.  <\/p>\n\n<h2 class=\"wp-block-heading\">La faille dans les exportations d&#8217;armes : Une couverture l\u00e9gale pour des actes ill\u00e9gaux  <\/h2>\n\n<p class=\"wp-block-paragraph\">Le Canada a adh\u00e9r\u00e9 au trait\u00e9 sur le commerce des armes (TCA) en 2019, ce qui l&#8217;oblige l\u00e9galement \u00e0 veiller \u00e0 ce que les exportations de biens militaires ne contribuent pas \u00e0 des violations du droit international.<sup data-fn=\"b2fb9366-6aaf-47ee-ba6b-6791bfb4a3c7\" class=\"fn\"><a id=\"b2fb9366-6aaf-47ee-ba6b-6791bfb4a3c7-link\" href=\"#b2fb9366-6aaf-47ee-ba6b-6791bfb4a3c7\">23<\/a><\/sup> Pourtant, le Canada continue d&#8217;<strong>exempter les \u00c9tats-Unis des contr\u00f4les \u00e0 l&#8217;exportation<\/strong> en vertu de la Loi sur les licences d&#8217;exportation et d&#8217;importation, ce qui permet aux composants d&#8217;armes fabriqu\u00e9s au Canada d&#8217;entrer dans les cha\u00eenes d&#8217;approvisionnement am\u00e9ricaines en grande partie sans contr\u00f4le.<sup data-fn=\"18e8fbc7-d530-412d-9359-e91272018f0d\" class=\"fn\"><a id=\"18e8fbc7-d530-412d-9359-e91272018f0d-link\" href=\"#18e8fbc7-d530-412d-9359-e91272018f0d\">24<\/a><\/sup> <\/p>\n\n<p class=\"wp-block-paragraph\">Selon Project Ploughshares, <strong>des composants canadiens ont \u00e9t\u00e9 trouv\u00e9s dans des syst\u00e8mes d&#8217;armes am\u00e9ricains d\u00e9ploy\u00e9s \u00e0 Gaza, au Y\u00e9men et maintenant dans les frappes militaires am\u00e9ricaines ill\u00e9gales sur des bateaux dans les Cara\u00efbes.<sup data-fn=\"c2c51535-e54d-441c-af25-be4d9bcfc413\" class=\"fn\"><a id=\"c2c51535-e54d-441c-af25-be4d9bcfc413-link\" href=\"#c2c51535-e54d-441c-af25-be4d9bcfc413\">25<\/a><\/sup> <\/strong> <\/p>\n\n<p class=\"wp-block-paragraph\">La licence g\u00e9n\u00e9rale d&#8217;exportation n\u00b0 47 (GEP-47) rationalise les exp\u00e9ditions d&#8217;articles contr\u00f4l\u00e9s par le TCA vers les \u00c9tats-Unis, o\u00f9 les pi\u00e8ces peuvent \u00eatre int\u00e9gr\u00e9es dans des armes et r\u00e9export\u00e9es avec beaucoup moins de visibilit\u00e9 et de contr\u00f4le de la part du Canada.<sup data-fn=\"b779352b-e546-4818-a2d8-6644c3053d40\" class=\"fn\"><a id=\"b779352b-e546-4818-a2d8-6644c3053d40-link\" href=\"#b779352b-e546-4818-a2d8-6644c3053d40\">26<\/a><\/sup> <\/p>\n\n<p class=\"wp-block-paragraph\">Alors que le Canada pr\u00e9tend d\u00e9fendre les droits de l&#8217;homme et une approche de sant\u00e9 publique en mati\u00e8re de politique des drogues, <strong>notre r\u00e9gime d&#8217;exportation permet activement l&#8217;utilisation de la force militaire contre des civils et garantit un d\u00e9ni plausible plut\u00f4t qu&#8217;une obligation de rendre des comptes.<\/strong> <\/p>\n\n<p class=\"wp-block-paragraph\">Le projet de <strong>loi C-233<\/strong> de la d\u00e9put\u00e9e Jenny Kwan vise \u00e0 combler cette lacune en supprimant les exemptions nationales, en exigeant des certificats d&#8217;utilisation finale et en rendant obligatoire la pr\u00e9sentation au Parlement d&#8217;un rapport annuel sur le respect du trait\u00e9 sur le commerce des armes.<sup data-fn=\"7244d459-d48f-4669-8c8c-456eb6514bf6\" class=\"fn\"><a id=\"7244d459-d48f-4669-8c8c-456eb6514bf6-link\" href=\"#7244d459-d48f-4669-8c8c-456eb6514bf6\">27<\/a><\/sup> Ce projet de loi repr\u00e9sente une \u00e9tape cruciale pour garantir que le Canada ne permette pas les violations des droits de l&#8217;homme \u00e0 l&#8217;\u00e9tranger.  <\/p>\n\n<h2 class=\"wp-block-heading\">La politique en mati\u00e8re de drogues doit respecter les droits de l&#8217;homme  <\/h2>\n\n<p class=\"wp-block-paragraph\">Le cadre juridique international est sans ambigu\u00eft\u00e9. <strong>La<a href=\"https:\/\/idpc.net\/blog\/2025\/10\/the-human-rights-council-asserts-its-role-in-drug-policy-at-a-time-of-global-change\">r\u00e9solution 60\/26<\/a><\/strong> <strong>du Conseil des droits de l&#8217;homme des Nations unies<\/strong> <strong>, adopt\u00e9e par consensus en 2025, fait des droits de l&#8217;homme &#8211; et non de la criminalisation &#8211; le cadre fondamental de la coop\u00e9ration internationale en mati\u00e8re de drogues.<\/strong><sup data-fn=\"b6ec0804-70a5-4cd4-9730-95a20060ddc3\" class=\"fn\"><a id=\"b6ec0804-70a5-4cd4-9730-95a20060ddc3-link\" href=\"#b6ec0804-70a5-4cd4-9730-95a20060ddc3\">28<\/a><\/sup><sup data-fn=\"200098e9-a70a-48ab-90bb-3b3c6bce2ee2\" class=\"fn\"><a id=\"200098e9-a70a-48ab-90bb-3b3c6bce2ee2-link\" href=\"#200098e9-a70a-48ab-90bb-3b3c6bce2ee2\">29<\/a><\/sup> La r\u00e9solution appelle les \u00c9tats \u00e0 int\u00e9grer la r\u00e9duction des m\u00e9faits dans les politiques de sant\u00e9 publique, \u00e0 respecter les droits des autochtones, \u00e0 s&#8217;attaquer aux m\u00e9faits environnementaux et \u00e0 prot\u00e9ger les acteurs de la soci\u00e9t\u00e9 civile qui travaillent sur la r\u00e9forme des drogues.   <\/p>\n\n<p class=\"wp-block-paragraph\">Cette r\u00e9solution affirme que la politique en mati\u00e8re de drogues fait partie int\u00e9grante du syst\u00e8me des droits de l&#8217;homme, plut\u00f4t que de relever uniquement d&#8217;organes charg\u00e9s de l&#8217;application de la loi tels que la Commission des stup\u00e9fiants. Pourtant, <strong>le Canada n&#8217;a pas pleinement approuv\u00e9 ou mis en \u0153uvre ce changement<\/strong>, bien qu&#8217;il soit li\u00e9 par les trait\u00e9s internationaux relatifs aux droits de l&#8217;homme, notamment le Pacte international relatif aux droits civils et politiques et le Pacte international relatif aux droits \u00e9conomiques, sociaux et culturels (PIDESC).   <\/p>\n\n<p class=\"wp-block-paragraph\">De m\u00eame, le rapport d&#8217;ao\u00fbt 2023 du Haut-Commissariat aux droits de l&#8217;homme, intitul\u00e9 &#8220;D\u00e9fis en mati\u00e8re de droits de l&#8217;homme dans le traitement et la lutte contre tous les aspects du probl\u00e8me mondial de la drogue&#8221;, invite les \u00c9tats membres \u00e0 envisager une r\u00e9glementation responsable des march\u00e9s de la drogue, ce qui s&#8217;\u00e9carte nettement de l&#8217;approche internationale militaris\u00e9e que le Canada soutient actuellement.<sup data-fn=\"5a33e2b6-7751-4406-97ce-b046a3b10d46\" class=\"fn\"><a id=\"5a33e2b6-7751-4406-97ce-b046a3b10d46-link\" href=\"#5a33e2b6-7751-4406-97ce-b046a3b10d46\">30<\/a><\/sup> <\/p>\n\n<p class=\"wp-block-paragraph\">Le rapporteur sp\u00e9cial des Nations unies sur le droit \u00e0 la sant\u00e9 a \u00e9t\u00e9 tout aussi clair : la r\u00e9duction des m\u00e9faits doit \u00eatre au c\u0153ur de la politique en mati\u00e8re de drogues, et les approches r\u00e9pressives qui violent le droit \u00e0 la sant\u00e9 sont incompatibles avec le droit international.<sup data-fn=\"4ec9fe2f-81db-45f0-8303-9ec5365fb74b\" class=\"fn\"><a id=\"4ec9fe2f-81db-45f0-8303-9ec5365fb74b-link\" href=\"#4ec9fe2f-81db-45f0-8303-9ec5365fb74b\">31<\/a><\/sup> <\/p>\n\n<h2 class=\"wp-block-heading\">L&#8217;hypocrisie \u00e0 la maison  <\/h2>\n\n<p class=\"wp-block-paragraph\">La contradiction est flagrante.  <strong>Au niveau national, le gouvernement f\u00e9d\u00e9ral se targue d&#8217;une approche de sant\u00e9 publique en mati\u00e8re de drogues. Dans la pratique, l&#8217;application de la loi et la militarisation dominent les d\u00e9penses. <\/strong><sup data-fn=\"58902e7c-1682-4ea0-9986-99465f741fb3\" class=\"fn\"><a id=\"58902e7c-1682-4ea0-9986-99465f741fb3-link\" href=\"#58902e7c-1682-4ea0-9986-99465f741fb3\">32<\/a><\/sup> En 2025, dans des tentatives infructueuses d&#8217;apaiser Trump, Ottawa a d\u00e9ploy\u00e9 un plan frontalier de 1,3 milliard de dollars, nomm\u00e9 un &#8220;tsar du fentanyl&#8221; f\u00e9d\u00e9ral et avanc\u00e9 des lois frontali\u00e8res agressives &#8211; des mesures qui augmentent consid\u00e9rablement les d\u00e9penses consacr\u00e9es \u00e0 l&#8217;application de la loi, alors que les communaut\u00e9s manquent toujours d&#8217;un financement stable pour le logement, les services de r\u00e9duction des m\u00e9faits et le traitement.<sup data-fn=\"c24a28fd-1b43-49b6-97a6-ee9f1ffd5704\" class=\"fn\"><a id=\"c24a28fd-1b43-49b6-97a6-ee9f1ffd5704-link\" href=\"#c24a28fd-1b43-49b6-97a6-ee9f1ffd5704\">33<\/a><\/sup> <\/p>\n\n<p class=\"wp-block-paragraph\">Pendant ce temps, la crise des m\u00e9dicaments toxiques non r\u00e9glement\u00e9s continue de tuer des milliers de Canadiens chaque ann\u00e9e.<sup data-fn=\"f21c9b71-7dc4-4412-bdec-f98e895a7740\" class=\"fn\"><a id=\"f21c9b71-7dc4-4412-bdec-f98e895a7740-link\" href=\"#f21c9b71-7dc4-4412-bdec-f98e895a7740\">34<\/a><\/sup> <strong>Chaque dollar d\u00e9pens\u00e9 pour l&#8217;application de la loi et les frappes militaires ill\u00e9gales est un dollar qui n&#8217;est pas d\u00e9pens\u00e9 pour ce dont les communaut\u00e9s ont besoin : la pr\u00e9vention des overdoses, une r\u00e9glementation responsable, le traitement volontaire \u00e0 la demande et le logement &#8211; des<\/strong>interventions <strong>qui ont fait leurs preuves<\/strong>et <strong>qui sont<\/strong>explicitement recommand\u00e9es par les directives des Nations unies en mati\u00e8re de droits de l&#8217;homme.  <\/p>\n\n<p class=\"wp-block-paragraph\">Cela refl\u00e8te le mod\u00e8le mondial : la prohibition ne parvient pas \u00e0 r\u00e9duire la consommation de drogues, mais r\u00e9ussit \u00e0 rendre la production clandestine, \u00e0 renforcer le crime organis\u00e9 et \u00e0 contribuer \u00e0 l&#8217;instabilit\u00e9, \u00e0 la violence et aux violations des droits de l&#8217;homme \u00e0 l&#8217;\u00e9tranger, tout en alimentant une crise toxique de la drogue \u00e0 l&#8217;int\u00e9rieur du pays.  <\/p>\n\n<h2 class=\"wp-block-heading\">Ce que le Canada doit faire maintenant  <\/h2>\n\n<p class=\"wp-block-paragraph\">Pour aligner ses politiques sur ses valeurs d\u00e9clar\u00e9es, le droit international et les droits de l&#8217;homme, le Canada doit.. :  <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>1. Mettre fin \u00e0 l&#8217;\u00e9chappatoire de l&#8217;exportation d&#8217;armes.<\/strong>  Adopter le projet de loi C-233 pour mettre fin \u00e0 l&#8217;exemption am\u00e9ricaine, rendre obligatoires les certificats d&#8217;utilisation finale et pr\u00e9senter au Parlement un rapport annuel sur le respect du TCA. La mise en \u0153uvre devrait inclure un plan de transition \u00e9quitable pour les travailleurs du secteur de la fabrication de mat\u00e9riel de d\u00e9fense.   <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>2. Suspendre la participation \u00e0 l&#8217;op\u00e9ration CARIBBE<\/strong> dans l&#8217;attente d&#8217;un examen juridique ind\u00e9pendant portant sur le respect du droit international et des normes en mati\u00e8re de droits de l&#8217;homme. Cet examen doit porter sur le partage des renseignements, l&#8217;autorit\u00e9 de commandement et les garanties contre les \u00e9quipements, logiciels et donn\u00e9es produits par le Canada et permettant des frappes l\u00e9tales.   <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>3. Approuver formellement et mettre en \u0153uvre la r\u00e9solution 60\/26 du Conseil des droits de l&#8217;homme des Nations unies<\/strong> dans le cadre de la strat\u00e9gie nationale antidrogue du Canada. Il s&#8217;agit notamment d&#8217;int\u00e9grer les principes de r\u00e9duction des m\u00e9faits, les droits des autochtones et la protection de l&#8217;environnement dans le droit national.   <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>4. R\u00e9orienter les fonds allou\u00e9s \u00e0 l&#8217;arm\u00e9e et aux forces de l&#8217;ordre vers des mesures de soutien communautaire qui ont fait leurs preuves.<\/strong>  R\u00e9affecter les fonds gaspill\u00e9s et nuisibles consacr\u00e9s \u00e0 l&#8217;application de la loi \u00e0 des mesures de soutien efficaces : pr\u00e9vention des overdoses, traitement volontaire \u00e0 la demande, logement, r\u00e9glementation responsable, salaires d\u00e9cents et services g\u00e9r\u00e9s par la communaut\u00e9. C&#8217;est exactement ce que recommandent les orientations des Nations unies en mati\u00e8re de droits de l&#8217;homme.   <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>5. Soutenir les rapports du HCDH sur l&#8217;impact des politiques en mati\u00e8re de drogues.<\/strong>  Contribuer au financement canadien d&#8217;\u00e9tudes sur la pauvret\u00e9, la race, le genre, les droits des autochtones et les dommages environnementaux li\u00e9s \u00e0 la politique en mati\u00e8re de drogues.  <\/p>\n\n<h2 class=\"wp-block-heading\">Le Canada doit choisir : affirmer ses valeurs ou soutenir le meurtre ordonn\u00e9 par Trump  <\/h2>\n\n<p class=\"wp-block-paragraph\">La v\u00e9ritable s\u00e9curit\u00e9 repose sur les faits, la sant\u00e9 et les droits de l&#8217;homme, et non sur la peur et la force. Chaque dollar, chaque choix politique et chaque d\u00e9cision diplomatique devrait refl\u00e9ter un principe fondamental : le droit \u00e0 la vie, \u00e0 la dignit\u00e9 et \u00e0 la sant\u00e9 n&#8217;est pas n\u00e9gociable.   <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Le fait de tuer des civils en mer est contraire au droit international et perp\u00e9tue les cycles de souffrance et de violence.  <\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">La participation du Canada aux frappes militaires men\u00e9es par les \u00c9tats-Unis semble d\u00e9montrer que notre souverainet\u00e9 et nos valeurs restent conditionn\u00e9es par les priorit\u00e9s am\u00e9ricaines. Pour \u00eatre \u00e0 la hauteur des principes que nous pr\u00e9tendons d\u00e9fendre, nos dirigeants \u00e9lus doivent prendre position : soutenir le cadre des droits de l&#8217;homme de l&#8217;ONU, combler les lacunes en mati\u00e8re d&#8217;exportation et mettre fin \u00e0 la complicit\u00e9 du Canada dans les meurtres extrajudiciaires.   <\/p>\n\n<h2 class=\"wp-block-heading\">Passez \u00e0 l&#8217;action  <\/h2>\n\n<p class=\"wp-block-paragraph\"><strong>Contactez votre d\u00e9put\u00e9<\/strong> pour soutenir le projet de loi C-233, exiger que le Canada se retire de l&#8217;op\u00e9ration CARIBBE jusqu&#8217;\u00e0 ce qu&#8217;un examen juridique ind\u00e9pendant soit effectu\u00e9, et insister pour que les fonds f\u00e9d\u00e9raux soient consacr\u00e9s \u00e0 la sant\u00e9 et au soutien des communaut\u00e9s, et non aux navires de guerre et aux frappes a\u00e9riennes qui tuent des civils.  <\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n<ol class=\"wp-block-footnotes has-x-small-font-size\"><li id=\"0ff9e067-370c-4ee1-a209-672bf18d1778\"><a href=\"https:\/\/www.amnesty.org\/en\/latest\/news\/2025\/10\/u-s-airstrikes-in-latin-america-and-the-caribbean-are-murder-congress-must-stop-them-now\/%20\">https:\/\/www.amnesty.org\/en\/latest\/news\/2025\/10\/u-s-airstrikes-in-latin-america-and-the-caribbean-are-murder-congress-must-stop-them-now\/\n <\/a> <a href=\"#0ff9e067-370c-4ee1-a209-672bf18d1778-link\" aria-label=\"Jump to footnote reference 1\">\u21a9\ufe0e<\/a><\/li><li id=\"6024ab37-7e94-400d-b291-781afa57f224\"><a href=\"https:\/\/www.cbc.ca\/news\/canada\/newfoundland-labrador\/us-airstrikes-caribbean-drug-smugglers-9.6932751\">https:\/\/www.cbc.ca\/news\/canada\/newfoundland-labrador\/us-airstrikes-caribbean-drug-smugglers-9.6932751<\/a> <a href=\"#6024ab37-7e94-400d-b291-781afa57f224-link\" aria-label=\"Jump to footnote reference 2\">\u21a9\ufe0e<\/a><\/li><li id=\"48564a98-e338-42eb-94db-aeecdc82fbde\"><a href=\"https:\/\/ploughshares.ca\/targeted-from-above-canadian-sensors-facilitating-unlawful-u-s-airstrikes-in-the-caribbean\/%20\">https:\/\/ploughshares.ca\/targeted-from-above-canadian-sensors-facilitating-unlawful-u-s-airstrikes-in-the-caribbean\/\n <\/a> <a href=\"#48564a98-e338-42eb-94db-aeecdc82fbde-link\" aria-label=\"Jump to footnote reference 3\">\u21a9\ufe0e<\/a><\/li><li id=\"0be014e6-9bf1-482b-848b-f1e91c845611\">La politique prohibitionniste en mati\u00e8re de drogues, aussi fr\u00e9quemment appel\u00e9e approche fond\u00e9e sur la criminalisation ou &#8220;guerre contre la drogue&#8221;, fait r\u00e9f\u00e9rence \u00e0 une s\u00e9rie de politiques, de pratiques et de lois introduites au cours du 20e si\u00e8cle qui criminalisent la consommation de drogues et les activit\u00e9s qui y sont associ\u00e9es. Bien que son objectif d\u00e9clar\u00e9 soit g\u00e9n\u00e9ralement de r\u00e9duire ou d&#8217;\u00e9liminer la consommation et la disponibilit\u00e9 des drogues, il est aujourd&#8217;hui largement reconnu non seulement qu&#8217;elle n&#8217;y est pas parvenue malgr\u00e9 des investissements publics massifs et soutenus, mais aussi qu&#8217;elle a eu de graves cons\u00e9quences n\u00e9gatives, ressenties de mani\u00e8re disproportionn\u00e9e par les communaut\u00e9s marginalis\u00e9es.  <a href=\"#0be014e6-9bf1-482b-848b-f1e91c845611-link\" aria-label=\"Jump to footnote reference 4\">\u21a9\ufe0e<\/a><\/li><li id=\"5fe209ac-9306-4fa2-9245-effc1cd2fd44\">On manque de donn\u00e9es d\u00e9montrant l&#8217;efficacit\u00e9 des efforts d&#8217;application de la loi au Canada.  <a href=\"https:\/\/www.canada.ca\/en\/health-canada\/corporate\/transparency\/corporate-management-reporting\/evaluation\/canadian-drugs-substances-strategy.html\">https:\/\/www.canada.ca\/en\/health-canada\/corporate\/transparency\/corporate-management-reporting\/evaluation\/canadian-drugs-substances-strategy.html<\/a> <a href=\"#5fe209ac-9306-4fa2-9245-effc1cd2fd44-link\" aria-label=\"Jump to footnote reference 5\">\u21a9\ufe0e<\/a><\/li><li id=\"d7118664-cd74-4bde-af50-f3199e56e258\">Dans un rapport publi\u00e9 en 2020, la Commission mondiale sur la politique des drogues a estim\u00e9 qu&#8217;il<a href=\"https:\/\/www.globalcommissionondrugs.org\/wp-content\/uploads\/2020\/06\/2020report_EN_web_100620.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">n&#8217;existait&#8221;aucune preuve solide que l&#8217;intensification de la r\u00e9pression augmente les co\u00fbts r\u00e9els pour les trafiquants de drogue<\/a>&#8221; <a href=\"#d7118664-cd74-4bde-af50-f3199e56e258-link\" aria-label=\"Jump to footnote reference 6\">\u21a9\ufe0e<\/a><\/li><li id=\"91a6d1b9-3e54-4347-a94b-5fbf65b15389\"><a href=\"https:\/\/www.healthpovertyaction.org\/wp-content\/uploads\/2023\/10\/REPORT-Revealing-the-Missing-Link-to-Climate-Justice-Drug-Policy.pdf%20\">https:\/\/www.healthpovertyaction.org\/wp-content\/uploads\/2023\/10\/REPORT-Revealing-the-Missing-Link-to-Climate-Justice-Drug-Policy.pdf\n <\/a> <a href=\"#91a6d1b9-3e54-4347-a94b-5fbf65b15389-link\" aria-label=\"Jump to footnote reference 7\">\u21a9\ufe0e<\/a><\/li><li id=\"a45e03bb-d460-43be-8b5c-a9e134eae88c\">En 2024, une \u00e9tude exploratoire publi\u00e9e dans l&#8217;International Journal of Drug Policy a trouv\u00e9 des &#8220;preuves coh\u00e9rentes que les mesures de saisie li\u00e9es au fentanyl&#8221; \u00e9taient associ\u00e9es \u00e0 une mortalit\u00e9 par overdose plus \u00e9lev\u00e9e. <a href=\"https:\/\/doi.org\/10.1016\/j.drugpo.2024.104321\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1016\/j.drugpo.2024.104321<\/a>  <a href=\"#a45e03bb-d460-43be-8b5c-a9e134eae88c-link\" aria-label=\"Jump to footnote reference 8\">\u21a9\ufe0e<\/a><\/li><li id=\"00ea1fe4-1771-403f-8d4a-b9a14be0c03f\"><a href=\"https:\/\/x.com\/RapidResponse47\/status\/1962955342523879613%20\">https:\/\/x.com\/RapidResponse47\/status\/1962955342523879613\n <\/a> <a href=\"#00ea1fe4-1771-403f-8d4a-b9a14be0c03f-link\" aria-label=\"Jump to footnote reference 9\">\u21a9\ufe0e<\/a><\/li><li id=\"fbf04cbf-01e3-45cc-b434-50a41c30a183\">Guardian, &#8220;Colombia urges US to halt strikes on alleged drug-smuggling boats : &#8216;It is murder'&#8221; (23 octobre 2025)   <a href=\"#fbf04cbf-01e3-45cc-b434-50a41c30a183-link\" aria-label=\"Jump to footnote reference 10\">\u21a9\ufe0e<\/a><\/li><li id=\"ab3c3897-772b-4c8b-8259-cef57adbc3fd\">ABC News, &#8220;Trump administration conducts military strikes on suspected drug-courier boats in the Pacific&#8221; (23 octobre 2025) <a href=\"#ab3c3897-772b-4c8b-8259-cef57adbc3fd-link\" aria-label=\"Jump to footnote reference 11\">\u21a9\ufe0e<\/a><\/li><li id=\"b135c1a8-6963-4124-9e2e-a781ef95edc9\">WOLA, &#8220;La frappe mortelle de l&#8217;arm\u00e9e am\u00e9ricaine sur des trafiquants de drogue pr\u00e9sum\u00e9s cr\u00e9e un dangereux pr\u00e9c\u00e9dent dans la &#8216;guerre contre la drogue'&#8221;   <a href=\"#b135c1a8-6963-4124-9e2e-a781ef95edc9-link\" aria-label=\"Jump to footnote reference 12\">\u21a9\ufe0e<\/a><\/li><li id=\"27a6594d-e23d-4eba-95bd-d186909c1384\"><a href=\"https:\/\/www.hrw.org\/news\/2025\/09\/18\/us-maritime-strikes-amount-to-extrajudicial-killings%20\">https:\/\/www.hrw.org\/news\/2025\/09\/18\/us-maritime-strikes-amount-to-extrajudicial-killings\n <\/a> <a href=\"#27a6594d-e23d-4eba-95bd-d186909c1384-link\" aria-label=\"Jump to footnote reference 13\">\u21a9\ufe0e<\/a><\/li><li id=\"bc1c9f36-57d2-46b9-9110-2c0deabbeae1\"><a href=\"https:\/\/www.npr.org\/2025\/10\/24\/nx-s1-5584173\/trump-drug-boats-venezuela-maduro%20\">https:\/\/www.npr.org\/2025\/10\/24\/nx-s1-5584173\/trump-drug-boats-venezuela-maduro\n <\/a> <a href=\"#bc1c9f36-57d2-46b9-9110-2c0deabbeae1-link\" aria-label=\"Jump to footnote reference 14\">\u21a9\ufe0e<\/a><\/li><li id=\"ddb96e48-4747-4b21-95b3-7a6eead53ac4\"><a href=\"https:\/\/www.justsecurity.org\/119985\/labels-ustify-lethal-force-venezuelan-boat-strike\/%20\">https:\/\/www.justsecurity.org\/119985\/labels-ustify-lethal-force-venezuelan-boat-strike\/\n <\/a> <a href=\"#ddb96e48-4747-4b21-95b3-7a6eead53ac4-link\" aria-label=\"Jump to footnote reference 15\">\u21a9\ufe0e<\/a><\/li><li id=\"f90f23e1-d5f2-4f87-a4ea-e80afc319880\">Human Rights Watch, &#8220;US : Maritime Strikes Amount to Extrajudicial Killings&#8221; (18 septembre 2025)   <a href=\"#f90f23e1-d5f2-4f87-a4ea-e80afc319880-link\" aria-label=\"Jump to footnote reference 16\">\u21a9\ufe0e<\/a><\/li><li id=\"a01fb4b5-ea82-4050-875d-43cb8bf9a7ab\"><a href=\"https:\/\/www.hrw.org\/news\/2025\/09\/18\/us-maritime-strikes-amount-to-extrajudicial-killings\">https:\/\/www.hrw.org\/news\/2025\/09\/18\/us-maritime-strikes-amount-to-extrajudicial-killings<\/a> <a href=\"#a01fb4b5-ea82-4050-875d-43cb8bf9a7ab-link\" aria-label=\"Jump to footnote reference 17\">\u21a9\ufe0e<\/a><\/li><li id=\"225719cf-d3ab-403d-8bd9-f0b77c3876fa\">ACLU\/MSNBC Opinion, &#8220;Les frappes de bateaux de Trump tuent des civils potentiellement innocents. Il faut les arr\u00eater&#8221; (15 octobre 2025)   <a href=\"#225719cf-d3ab-403d-8bd9-f0b77c3876fa-link\" aria-label=\"Jump to footnote reference 18\">\u21a9\ufe0e<\/a><\/li><li id=\"27518e5d-b427-48b2-839f-0f020b5492fe\"><a href=\"https:\/\/www.canada.ca\/en\/department-national-defence\/services\/operations\/military-operations\/current-operations\/operation-caribbe.html\">Gouvernement du Canada, minist\u00e8re de la D\u00e9fense nationale, &#8220;Op\u00e9ration CARIBBE&#8221;<\/a> <a href=\"#27518e5d-b427-48b2-839f-0f020b5492fe-link\" aria-label=\"Jump to footnote reference 19\">\u21a9\ufe0e<\/a><\/li><li id=\"9efec4f6-756f-4eae-99f3-d25c211f944c\"><a href=\"https:\/\/www.canada.ca\/en\/department-national-defence\/corporate\/reports-publications\/departmental-plans\/departmental-plan-2025-26\/planned-costs-major-caf-operations.html%20\">https:\/\/www.canada.ca\/en\/department-national-defence\/corporate\/reports-publications\/departmental-plans\/departmental-plan-2025-26\/planned-costs-major-caf-operations.html\n <\/a> <a href=\"#9efec4f6-756f-4eae-99f3-d25c211f944c-link\" aria-label=\"Jump to footnote reference 20\">\u21a9\ufe0e<\/a><\/li><li id=\"80d4825b-b73e-4dcd-bc57-77fe3fe64376\"><a href=\"https:\/\/ploughshares.ca\/targeted-from-above-canadian-sensors-facilitating-unlawful-u-s-airstrikes-in-the-caribbean\/%20\">https:\/\/ploughshares.ca\/targeted-from-above-canadian-sensors-facilitating-unlawful-u-s-airstrikes-in-the-caribbean\/\n <\/a> <a href=\"#80d4825b-b73e-4dcd-bc57-77fe3fe64376-link\" aria-label=\"Jump to footnote reference 21\">\u21a9\ufe0e<\/a><\/li><li id=\"845f0db9-1c4c-4677-988c-669a87423ba1\"><a href=\"https:\/\/www.cbc.ca\/news\/canada\/canadian-miliary-technology-1.7650129%20\">https:\/\/www.cbc.ca\/news\/canada\/canadian-miliary-technology-1.7650129\n <\/a> <a href=\"#845f0db9-1c4c-4677-988c-669a87423ba1-link\" aria-label=\"Jump to footnote reference 22\">\u21a9\ufe0e<\/a><\/li><li id=\"b2fb9366-6aaf-47ee-ba6b-6791bfb4a3c7\"><a href=\"https:\/\/www.thearmstradetreaty.org\/hyper-images\/file\/TheArmsTradeTreaty1\/TheArmsTradeTreaty.pdf%20\">https:\/\/www.thearmstradetreaty.org\/hyper-images\/file\/TheArmsTradeTreaty1\/TheArmsTradeTreaty.pdf\n <\/a> <a href=\"#b2fb9366-6aaf-47ee-ba6b-6791bfb4a3c7-link\" aria-label=\"Jump to footnote reference 23\">\u21a9\ufe0e<\/a><\/li><li id=\"18e8fbc7-d530-412d-9359-e91272018f0d\"><a href=\"https:\/\/laws-lois.justice.gc.ca\/eng\/acts\/e-19\/%20\">https:\/\/laws-lois.justice.gc.ca\/eng\/acts\/e-19\/\n <\/a> <a href=\"#18e8fbc7-d530-412d-9359-e91272018f0d-link\" aria-label=\"Jump to footnote reference 24\">\u21a9\ufe0e<\/a><\/li><li id=\"c2c51535-e54d-441c-af25-be4d9bcfc413\"><a href=\"https:\/\/ploughshares.ca\/targeted-from-above-canadian-sensors-facilitating-unlawful-u-s-airstrikes-in-the-caribbean\/%20\">https:\/\/ploughshares.ca\/targeted-from-above-canadian-sensors-facilitating-unlawful-u-s-airstrikes-in-the-caribbean\/\n <\/a> <a href=\"#c2c51535-e54d-441c-af25-be4d9bcfc413-link\" aria-label=\"Jump to footnote reference 25\">\u21a9\ufe0e<\/a><\/li><li id=\"b779352b-e546-4818-a2d8-6644c3053d40\"><a href=\"https:\/\/laws-lois.justice.gc.ca\/eng\/regulations\/SOR-2019-230\/index.html%20\">https:\/\/laws-lois.justice.gc.ca\/eng\/regulations\/SOR-2019-230\/index.html\n <\/a> <a href=\"#b779352b-e546-4818-a2d8-6644c3053d40-link\" aria-label=\"Jump to footnote reference 26\">\u21a9\ufe0e<\/a><\/li><li id=\"7244d459-d48f-4669-8c8c-456eb6514bf6\"><a href=\"https:\/\/www.parl.ca\/legisinfo\/en\/bill\/45-1\/c-233%20\">https:\/\/www.parl.ca\/legisinfo\/en\/bill\/45-1\/c-233\n <\/a> <a href=\"#7244d459-d48f-4669-8c8c-456eb6514bf6-link\" aria-label=\"Jump to footnote reference 27\">\u21a9\ufe0e<\/a><\/li><li id=\"b6ec0804-70a5-4cd4-9730-95a20060ddc3\"><a href=\"https:\/\/docs.un.org\/en\/A\/HRC\/RES\/60\/26\">https:\/\/docs.un.org\/en\/A\/HRC\/RES\/60\/26<\/a> <a href=\"#b6ec0804-70a5-4cd4-9730-95a20060ddc3-link\" aria-label=\"Jump to footnote reference 28\">\u21a9\ufe0e<\/a><\/li><li id=\"200098e9-a70a-48ab-90bb-3b3c6bce2ee2\"><a href=\"https:\/\/idpc.net\/blog\/2025\/10\/the-human-rights-council-asserts-its-role-in-drug-policy-at-a-time-of-global-change%20\">https:\/\/idpc.net\/blog\/2025\/10\/the-human-rights-council-asserts-its-role-in-drug-policy-at-a-time-of-global-change\n <\/a> <a href=\"#200098e9-a70a-48ab-90bb-3b3c6bce2ee2-link\" aria-label=\"Jump to footnote reference 29\">\u21a9\ufe0e<\/a><\/li><li id=\"5a33e2b6-7751-4406-97ce-b046a3b10d46\"><a href=\"https:\/\/www.ohchr.org\/en\/documents\/thematic-reports\/ahrc5453-human-rights-challenges-addressing-and-countering-all-aspects%20\">https:\/\/www.ohchr.org\/en\/documents\/thematic-reports\/ahrc5453-human-rights-challenges-addressing-and-countering-all-aspects\n <\/a> <a href=\"#5a33e2b6-7751-4406-97ce-b046a3b10d46-link\" aria-label=\"Jump to footnote reference 30\">\u21a9\ufe0e<\/a><\/li><li id=\"4ec9fe2f-81db-45f0-8303-9ec5365fb74b\"><a href=\"https:\/\/www.ohchr.org\/en\/documents\/thematic-reports\/ahrc5652-drug-use-harm-reduction-and-right-health-report-special%20\">https:\/\/www.ohchr.org\/en\/documents\/thematic-reports\/ahrc5652-drug-use-harm-reduction-and-right-health-report-special\n <\/a> <a href=\"#4ec9fe2f-81db-45f0-8303-9ec5365fb74b-link\" aria-label=\"Jump to footnote reference 31\">\u21a9\ufe0e<\/a><\/li><li id=\"58902e7c-1682-4ea0-9986-99465f741fb3\">L&#8217;<strong>\u00e9valuation horizontale 2023<\/strong> de la Strat\u00e9gie canadienne relative aux drogues et aux substances (SDCS) a r\u00e9v\u00e9l\u00e9 que, m\u00eame avant les r\u00e9centes annonces de financement, l&#8217;application de la loi consommait d\u00e9j\u00e0 <strong>58 % des fonds f\u00e9d\u00e9raux<\/strong>, contre seulement 18 % pour la pr\u00e9vention, 13 % pour le traitement, 8 % pour la r\u00e9duction des m\u00e9faits et 3 % pour la recherche. https:\/\/www. <a href=\"https:\/\/www.canada.ca\/en\/health-canada\/corporate\/transparency\/corporate-management-reporting\/evaluation\/canadian-drugs-substances-strategy.html\">canada.ca\/en\/health-canada\/corporate\/transparency\/corporate-management-reporting\/evaluation\/canadian-drugs-substances-strategy.html<\/a>  <a href=\"#58902e7c-1682-4ea0-9986-99465f741fb3-link\" aria-label=\"Jump to footnote reference 32\">\u21a9\ufe0e<\/a><\/li><li id=\"c24a28fd-1b43-49b6-97a6-ee9f1ffd5704\"><a href=\"https:\/\/www.canada.ca\/en\/public-safety-canada\/news\/2024\/12\/the-government-of-canadas-border-plan-significant-investments-to-strengthen-border-security-and-our-immigration-system.html%20\">https:\/\/www.canada.ca\/en\/public-safety-canada\/news\/2024\/12\/the-government-of-canadas-border-plan-significant-investments-to-strengthen-border-security-and-our-immigration-system.html\n <\/a> <a href=\"#c24a28fd-1b43-49b6-97a6-ee9f1ffd5704-link\" aria-label=\"Jump to footnote reference 33\">\u21a9\ufe0e<\/a><\/li><li id=\"f21c9b71-7dc4-4412-bdec-f98e895a7740\"><a href=\"https:\/\/health-infobase.canada.ca\/substance-related-harms\/opioids-stimulants\/%20\">https:\/\/health-infobase.canada.ca\/substance-related-harms\/opioids-stimulants\/\n <\/a> <a href=\"#f21c9b71-7dc4-4412-bdec-f98e895a7740-link\" aria-label=\"Jump to footnote reference 34\">\u21a9\ufe0e<\/a><\/li><\/ol>","protected":false},"excerpt":{"rendered":"<p>Depuis le 2 septembre 2025, l&#8217;arm\u00e9e am\u00e9ricaine a tu\u00e9 au moins 57 civils dans les eaux internationales, lors de frappes que le droit international et les autorit\u00e9s charg\u00e9es des droits de l&#8217;homme ont condamn\u00e9es comme \u00e9tant ill\u00e9gales.1 Des preuves de plus en plus nombreuses d\u00e9montrent l&#8217;implication importante du Canada dans ces op\u00e9rations militaires men\u00e9es par [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":22268,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","footnotes":"[{\"content\":\"<a href=\\\"https:\\\/\\\/www.amnesty.org\\\/en\\\/latest\\\/news\\\/2025\\\/10\\\/u-s-airstrikes-in-latin-america-and-the-caribbean-are-murder-congress-must-stop-them-now\\\/%20\\\">https:\\\/\\\/www.amnesty.org\\\/en\\\/latest\\\/news\\\/2025\\\/10\\\/u-s-airstrikes-in-latin-america-and-the-caribbean-are-murder-congress-must-stop-them-now\\\/\\n <\\\/a>\",\"id\":\"0ff9e067-370c-4ee1-a209-672bf18d1778\"},{\"content\":\"<a href=\\\"https:\\\/\\\/www.cbc.ca\\\/news\\\/canada\\\/newfoundland-labrador\\\/us-airstrikes-caribbean-drug-smugglers-9.6932751\\\">https:\\\/\\\/www.cbc.ca\\\/news\\\/canada\\\/newfoundland-labrador\\\/us-airstrikes-caribbean-drug-smugglers-9.6932751<\\\/a>\",\"id\":\"6024ab37-7e94-400d-b291-781afa57f224\"},{\"content\":\"<a href=\\\"https:\\\/\\\/ploughshares.ca\\\/targeted-from-above-canadian-sensors-facilitating-unlawful-u-s-airstrikes-in-the-caribbean\\\/%20\\\">https:\\\/\\\/ploughshares.ca\\\/targeted-from-above-canadian-sensors-facilitating-unlawful-u-s-airstrikes-in-the-caribbean\\\/\\n <\\\/a>\",\"id\":\"48564a98-e338-42eb-94db-aeecdc82fbde\"},{\"content\":\"La politique prohibitionniste en mati\\u00e8re de drogues, aussi fr\\u00e9quemment appel\\u00e9e approche fond\\u00e9e sur la criminalisation ou \\\"guerre contre la drogue\\\", fait r\\u00e9f\\u00e9rence \\u00e0 une s\\u00e9rie de politiques, de pratiques et de lois introduites au cours du 20e si\\u00e8cle qui criminalisent la consommation de drogues et les activit\\u00e9s qui y sont associ\\u00e9es. Bien que son objectif d\\u00e9clar\\u00e9 soit g\\u00e9n\\u00e9ralement de r\\u00e9duire ou d'\\u00e9liminer la consommation et la disponibilit\\u00e9 des drogues, il est aujourd'hui largement reconnu non seulement qu'elle n'y est pas parvenue malgr\\u00e9 des investissements publics massifs et soutenus, mais aussi qu'elle a eu de graves cons\\u00e9quences n\\u00e9gatives, ressenties de mani\\u00e8re disproportionn\\u00e9e par les communaut\\u00e9s marginalis\\u00e9es. \",\"id\":\"0be014e6-9bf1-482b-848b-f1e91c845611\"},{\"content\":\"On manque de donn\\u00e9es d\\u00e9montrant l'efficacit\\u00e9 des efforts d'application de la loi au Canada.  <a href=\\\"https:\\\/\\\/www.canada.ca\\\/en\\\/health-canada\\\/corporate\\\/transparency\\\/corporate-management-reporting\\\/evaluation\\\/canadian-drugs-substances-strategy.html\\\">https:\\\/\\\/www.canada.ca\\\/en\\\/health-canada\\\/corporate\\\/transparency\\\/corporate-management-reporting\\\/evaluation\\\/canadian-drugs-substances-strategy.html<\\\/a>\",\"id\":\"5fe209ac-9306-4fa2-9245-effc1cd2fd44\"},{\"content\":\"Dans un rapport publi\\u00e9 en 2020, la Commission mondiale sur la politique des drogues a estim\\u00e9 qu'il<a href=\\\"https:\\\/\\\/www.globalcommissionondrugs.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/2020report_EN_web_100620.pdf\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">n'existait\\\"aucune preuve solide que l'intensification de la r\\u00e9pression augmente les co\\u00fbts r\\u00e9els pour les trafiquants de drogue<\\\/a>\\\"\",\"id\":\"d7118664-cd74-4bde-af50-f3199e56e258\"},{\"content\":\"<a href=\\\"https:\\\/\\\/www.healthpovertyaction.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/REPORT-Revealing-the-Missing-Link-to-Climate-Justice-Drug-Policy.pdf%20\\\">https:\\\/\\\/www.healthpovertyaction.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/REPORT-Revealing-the-Missing-Link-to-Climate-Justice-Drug-Policy.pdf\\n <\\\/a>\",\"id\":\"91a6d1b9-3e54-4347-a94b-5fbf65b15389\"},{\"content\":\"En 2024, une \\u00e9tude exploratoire publi\\u00e9e dans l'International Journal of Drug Policy a trouv\\u00e9 des \\\"preuves coh\\u00e9rentes que les mesures de saisie li\\u00e9es au fentanyl\\\" \\u00e9taient associ\\u00e9es \\u00e0 une mortalit\\u00e9 par overdose plus \\u00e9lev\\u00e9e. <a href=\\\"https:\\\/\\\/doi.org\\\/10.1016\\\/j.drugpo.2024.104321\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">https:\\\/\\\/doi.org\\\/10.1016\\\/j.drugpo.2024.104321<\\\/a> \",\"id\":\"a45e03bb-d460-43be-8b5c-a9e134eae88c\"},{\"content\":\"<a href=\\\"https:\\\/\\\/x.com\\\/RapidResponse47\\\/status\\\/1962955342523879613%20\\\">https:\\\/\\\/x.com\\\/RapidResponse47\\\/status\\\/1962955342523879613\\n <\\\/a>\",\"id\":\"00ea1fe4-1771-403f-8d4a-b9a14be0c03f\"},{\"content\":\"Guardian, \\\"Colombia urges US to halt strikes on alleged drug-smuggling boats : 'It is murder'\\\" (23 octobre 2025)  \",\"id\":\"fbf04cbf-01e3-45cc-b434-50a41c30a183\"},{\"content\":\"ABC News, \\\"Trump administration conducts military strikes on suspected drug-courier boats in the Pacific\\\" (23 octobre 2025)\",\"id\":\"ab3c3897-772b-4c8b-8259-cef57adbc3fd\"},{\"content\":\"WOLA, \\\"La frappe mortelle de l'arm\\u00e9e am\\u00e9ricaine sur des trafiquants de drogue pr\\u00e9sum\\u00e9s cr\\u00e9e un dangereux pr\\u00e9c\\u00e9dent dans la 'guerre contre la drogue'\\\"  \",\"id\":\"b135c1a8-6963-4124-9e2e-a781ef95edc9\"},{\"content\":\"<a href=\\\"https:\\\/\\\/www.hrw.org\\\/news\\\/2025\\\/09\\\/18\\\/us-maritime-strikes-amount-to-extrajudicial-killings%20\\\">https:\\\/\\\/www.hrw.org\\\/news\\\/2025\\\/09\\\/18\\\/us-maritime-strikes-amount-to-extrajudicial-killings\\n <\\\/a>\",\"id\":\"27a6594d-e23d-4eba-95bd-d186909c1384\"},{\"content\":\"<a href=\\\"https:\\\/\\\/www.npr.org\\\/2025\\\/10\\\/24\\\/nx-s1-5584173\\\/trump-drug-boats-venezuela-maduro%20\\\">https:\\\/\\\/www.npr.org\\\/2025\\\/10\\\/24\\\/nx-s1-5584173\\\/trump-drug-boats-venezuela-maduro\\n <\\\/a>\",\"id\":\"bc1c9f36-57d2-46b9-9110-2c0deabbeae1\"},{\"content\":\"<a href=\\\"https:\\\/\\\/www.justsecurity.org\\\/119985\\\/labels-ustify-lethal-force-venezuelan-boat-strike\\\/%20\\\">https:\\\/\\\/www.justsecurity.org\\\/119985\\\/labels-ustify-lethal-force-venezuelan-boat-strike\\\/\\n <\\\/a>\",\"id\":\"ddb96e48-4747-4b21-95b3-7a6eead53ac4\"},{\"content\":\"Human Rights Watch, \\\"US : Maritime Strikes Amount to Extrajudicial Killings\\\" (18 septembre 2025)  \",\"id\":\"f90f23e1-d5f2-4f87-a4ea-e80afc319880\"},{\"content\":\"<a href=\\\"https:\\\/\\\/www.hrw.org\\\/news\\\/2025\\\/09\\\/18\\\/us-maritime-strikes-amount-to-extrajudicial-killings\\\">https:\\\/\\\/www.hrw.org\\\/news\\\/2025\\\/09\\\/18\\\/us-maritime-strikes-amount-to-extrajudicial-killings<\\\/a>\",\"id\":\"a01fb4b5-ea82-4050-875d-43cb8bf9a7ab\"},{\"content\":\"ACLU\\\/MSNBC Opinion, \\\"Les frappes de bateaux de Trump tuent des civils potentiellement innocents. Il faut les arr\\u00eater\\\" (15 octobre 2025)  \",\"id\":\"225719cf-d3ab-403d-8bd9-f0b77c3876fa\"},{\"content\":\"<a href=\\\"https:\\\/\\\/www.canada.ca\\\/en\\\/department-national-defence\\\/services\\\/operations\\\/military-operations\\\/current-operations\\\/operation-caribbe.html\\\">Gouvernement du Canada, minist\\u00e8re de la D\\u00e9fense nationale, \\\"Op\\u00e9ration CARIBBE\\\"<\\\/a>\",\"id\":\"27518e5d-b427-48b2-839f-0f020b5492fe\"},{\"content\":\"<a href=\\\"https:\\\/\\\/www.canada.ca\\\/en\\\/department-national-defence\\\/corporate\\\/reports-publications\\\/departmental-plans\\\/departmental-plan-2025-26\\\/planned-costs-major-caf-operations.html%20\\\">https:\\\/\\\/www.canada.ca\\\/en\\\/department-national-defence\\\/corporate\\\/reports-publications\\\/departmental-plans\\\/departmental-plan-2025-26\\\/planned-costs-major-caf-operations.html\\n <\\\/a>\",\"id\":\"9efec4f6-756f-4eae-99f3-d25c211f944c\"},{\"content\":\"<a href=\\\"https:\\\/\\\/ploughshares.ca\\\/targeted-from-above-canadian-sensors-facilitating-unlawful-u-s-airstrikes-in-the-caribbean\\\/%20\\\">https:\\\/\\\/ploughshares.ca\\\/targeted-from-above-canadian-sensors-facilitating-unlawful-u-s-airstrikes-in-the-caribbean\\\/\\n <\\\/a>\",\"id\":\"80d4825b-b73e-4dcd-bc57-77fe3fe64376\"},{\"content\":\"<a href=\\\"https:\\\/\\\/www.cbc.ca\\\/news\\\/canada\\\/canadian-miliary-technology-1.7650129%20\\\">https:\\\/\\\/www.cbc.ca\\\/news\\\/canada\\\/canadian-miliary-technology-1.7650129\\n <\\\/a>\",\"id\":\"845f0db9-1c4c-4677-988c-669a87423ba1\"},{\"content\":\"<a href=\\\"https:\\\/\\\/www.thearmstradetreaty.org\\\/hyper-images\\\/file\\\/TheArmsTradeTreaty1\\\/TheArmsTradeTreaty.pdf%20\\\">https:\\\/\\\/www.thearmstradetreaty.org\\\/hyper-images\\\/file\\\/TheArmsTradeTreaty1\\\/TheArmsTradeTreaty.pdf\\n <\\\/a>\",\"id\":\"b2fb9366-6aaf-47ee-ba6b-6791bfb4a3c7\"},{\"content\":\"<a href=\\\"https:\\\/\\\/laws-lois.justice.gc.ca\\\/eng\\\/acts\\\/e-19\\\/%20\\\">https:\\\/\\\/laws-lois.justice.gc.ca\\\/eng\\\/acts\\\/e-19\\\/\\n <\\\/a>\",\"id\":\"18e8fbc7-d530-412d-9359-e91272018f0d\"},{\"content\":\"<a href=\\\"https:\\\/\\\/ploughshares.ca\\\/targeted-from-above-canadian-sensors-facilitating-unlawful-u-s-airstrikes-in-the-caribbean\\\/%20\\\">https:\\\/\\\/ploughshares.ca\\\/targeted-from-above-canadian-sensors-facilitating-unlawful-u-s-airstrikes-in-the-caribbean\\\/\\n <\\\/a>\",\"id\":\"c2c51535-e54d-441c-af25-be4d9bcfc413\"},{\"content\":\"<a href=\\\"https:\\\/\\\/laws-lois.justice.gc.ca\\\/eng\\\/regulations\\\/SOR-2019-230\\\/index.html%20\\\">https:\\\/\\\/laws-lois.justice.gc.ca\\\/eng\\\/regulations\\\/SOR-2019-230\\\/index.html\\n <\\\/a>\",\"id\":\"b779352b-e546-4818-a2d8-6644c3053d40\"},{\"content\":\"<a href=\\\"https:\\\/\\\/www.parl.ca\\\/legisinfo\\\/en\\\/bill\\\/45-1\\\/c-233%20\\\">https:\\\/\\\/www.parl.ca\\\/legisinfo\\\/en\\\/bill\\\/45-1\\\/c-233\\n <\\\/a>\",\"id\":\"7244d459-d48f-4669-8c8c-456eb6514bf6\"},{\"content\":\"<a href=\\\"https:\\\/\\\/docs.un.org\\\/en\\\/A\\\/HRC\\\/RES\\\/60\\\/26\\\">https:\\\/\\\/docs.un.org\\\/en\\\/A\\\/HRC\\\/RES\\\/60\\\/26<\\\/a>\",\"id\":\"b6ec0804-70a5-4cd4-9730-95a20060ddc3\"},{\"content\":\"<a href=\\\"https:\\\/\\\/idpc.net\\\/blog\\\/2025\\\/10\\\/the-human-rights-council-asserts-its-role-in-drug-policy-at-a-time-of-global-change%20\\\">https:\\\/\\\/idpc.net\\\/blog\\\/2025\\\/10\\\/the-human-rights-council-asserts-its-role-in-drug-policy-at-a-time-of-global-change\\n <\\\/a>\",\"id\":\"200098e9-a70a-48ab-90bb-3b3c6bce2ee2\"},{\"content\":\"<a href=\\\"https:\\\/\\\/www.ohchr.org\\\/en\\\/documents\\\/thematic-reports\\\/ahrc5453-human-rights-challenges-addressing-and-countering-all-aspects%20\\\">https:\\\/\\\/www.ohchr.org\\\/en\\\/documents\\\/thematic-reports\\\/ahrc5453-human-rights-challenges-addressing-and-countering-all-aspects\\n <\\\/a>\",\"id\":\"5a33e2b6-7751-4406-97ce-b046a3b10d46\"},{\"content\":\"<a href=\\\"https:\\\/\\\/www.ohchr.org\\\/en\\\/documents\\\/thematic-reports\\\/ahrc5652-drug-use-harm-reduction-and-right-health-report-special%20\\\">https:\\\/\\\/www.ohchr.org\\\/en\\\/documents\\\/thematic-reports\\\/ahrc5652-drug-use-harm-reduction-and-right-health-report-special\\n <\\\/a>\",\"id\":\"4ec9fe2f-81db-45f0-8303-9ec5365fb74b\"},{\"content\":\"L'<strong>\\u00e9valuation horizontale 2023<\\\/strong> de la Strat\\u00e9gie canadienne relative aux drogues et aux substances (SDCS) a r\\u00e9v\\u00e9l\\u00e9 que, m\\u00eame avant les r\\u00e9centes annonces de financement, l'application de la loi consommait d\\u00e9j\\u00e0 <strong>58 % des fonds f\\u00e9d\\u00e9raux<\\\/strong>, contre seulement 18 % pour la pr\\u00e9vention, 13 % pour le traitement, 8 % pour la r\\u00e9duction des m\\u00e9faits et 3 % pour la recherche. https:\\\/\\\/www. <a href=\\\"https:\\\/\\\/www.canada.ca\\\/en\\\/health-canada\\\/corporate\\\/transparency\\\/corporate-management-reporting\\\/evaluation\\\/canadian-drugs-substances-strategy.html\\\">canada.ca\\\/en\\\/health-canada\\\/corporate\\\/transparency\\\/corporate-management-reporting\\\/evaluation\\\/canadian-drugs-substances-strategy.html<\\\/a> \",\"id\":\"58902e7c-1682-4ea0-9986-99465f741fb3\"},{\"content\":\"<a href=\\\"https:\\\/\\\/www.canada.ca\\\/en\\\/public-safety-canada\\\/news\\\/2024\\\/12\\\/the-government-of-canadas-border-plan-significant-investments-to-strengthen-border-security-and-our-immigration-system.html%20\\\">https:\\\/\\\/www.canada.ca\\\/en\\\/public-safety-canada\\\/news\\\/2024\\\/12\\\/the-government-of-canadas-border-plan-significant-investments-to-strengthen-border-security-and-our-immigration-system.html\\n <\\\/a>\",\"id\":\"c24a28fd-1b43-49b6-97a6-ee9f1ffd5704\"},{\"content\":\"<a href=\\\"https:\\\/\\\/health-infobase.canada.ca\\\/substance-related-harms\\\/opioids-stimulants\\\/%20\\\">https:\\\/\\\/health-infobase.canada.ca\\\/substance-related-harms\\\/opioids-stimulants\\\/\\n <\\\/a>\",\"id\":\"f21c9b71-7dc4-4412-bdec-f98e895a7740\"}]"},"categories":[33,7],"tags":[],"class_list":["post-22256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-international-fr","category-non-classifiee"],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Complicit\u00e9 du Canada avec les frappes militaires ill\u00e9gales des \u00c9tats-Unis : Quand la politique de sant\u00e9 publique en mati\u00e8re de drogues rencontre les ex\u00e9cutions extrajudiciaires - Canadian Drug Policy Coalition<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.drugpolicy.ca\/fr\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Complicit\u00e9 du Canada avec les frappes militaires ill\u00e9gales des \u00c9tats-Unis : Quand la politique de sant\u00e9 publique en mati\u00e8re de drogues rencontre les ex\u00e9cutions extrajudiciaires - Canadian Drug Policy Coalition\" \/>\n<meta property=\"og:description\" content=\"Depuis le 2 septembre 2025, l&#8217;arm\u00e9e am\u00e9ricaine a tu\u00e9 au moins 57 civils dans les eaux internationales, lors de frappes que le droit international et les autorit\u00e9s charg\u00e9es des droits de l&#8217;homme ont condamn\u00e9es comme \u00e9tant ill\u00e9gales.1 Des preuves de plus en plus nombreuses d\u00e9montrent l&#8217;implication importante du Canada dans ces op\u00e9rations militaires men\u00e9es par [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.drugpolicy.ca\/fr\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/\" \/>\n<meta property=\"og:site_name\" content=\"Canadian Drug Policy Coalition\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-28T16:11:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T18:41:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drugpolicy.ca\/wp-content\/uploads\/2026\/01\/blog-post-template.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Canadian Drug Policy Coalition\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canadian Drug Policy Coalition\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\\\/\"},\"author\":{\"name\":\"Canadian Drug Policy Coalition\",\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#\\\/schema\\\/person\\\/c32110f234bdb1f5d978710b6b406a30\"},\"headline\":\"Complicit\u00e9 du Canada avec les frappes militaires ill\u00e9gales des \u00c9tats-Unis : Quand la politique de sant\u00e9 publique en mati\u00e8re de drogues rencontre les ex\u00e9cutions extrajudiciaires\",\"datePublished\":\"2026-01-28T16:11:32+00:00\",\"dateModified\":\"2026-02-02T18:41:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\\\/\"},\"wordCount\":2734,\"publisher\":{\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.drugpolicy.ca\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/blog-post-template.png\",\"articleSection\":[\"International\",\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\\\/\",\"url\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\\\/\",\"name\":\"Complicit\u00e9 du Canada avec les frappes militaires ill\u00e9gales des \u00c9tats-Unis : Quand la politique de sant\u00e9 publique en mati\u00e8re de drogues rencontre les ex\u00e9cutions extrajudiciaires - Canadian Drug Policy Coalition\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.drugpolicy.ca\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/blog-post-template.png\",\"datePublished\":\"2026-01-28T16:11:32+00:00\",\"dateModified\":\"2026-02-02T18:41:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.drugpolicy.ca\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/blog-post-template.png\",\"contentUrl\":\"https:\\\/\\\/www.drugpolicy.ca\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/blog-post-template.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/drugpolicy.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Complicit\u00e9 du Canada avec les frappes militaires ill\u00e9gales des \u00c9tats-Unis : Quand la politique de sant\u00e9 publique en mati\u00e8re de drogues rencontre les ex\u00e9cutions extrajudiciaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#website\",\"url\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/\",\"name\":\"Canadian Drug Policy Coalition\",\"description\":\"Change policy. Save lives.\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#organization\",\"name\":\"Canadian Drug Policy Coalition\",\"url\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/drugpolicy.ca\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/CDPC-logo-white-on-red-150-dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/drugpolicy.ca\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/CDPC-logo-white-on-red-150-dpi.jpg\",\"width\":332,\"height\":333,\"caption\":\"Canadian Drug Policy Coalition\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#\\\/schema\\\/person\\\/c32110f234bdb1f5d978710b6b406a30\",\"name\":\"Canadian Drug Policy Coalition\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g\",\"caption\":\"Canadian Drug Policy Coalition\"},\"description\":\"Advocating for public health- and human rights-based drug policy grounded in evidence, compassion, and social justice\",\"url\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/author\\\/canadian-drug-policy-coalition\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Complicit\u00e9 du Canada avec les frappes militaires ill\u00e9gales des \u00c9tats-Unis : Quand la politique de sant\u00e9 publique en mati\u00e8re de drogues rencontre les ex\u00e9cutions extrajudiciaires - Canadian Drug Policy Coalition","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.drugpolicy.ca\/fr\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/","og_locale":"fr_FR","og_type":"article","og_title":"Complicit\u00e9 du Canada avec les frappes militaires ill\u00e9gales des \u00c9tats-Unis : Quand la politique de sant\u00e9 publique en mati\u00e8re de drogues rencontre les ex\u00e9cutions extrajudiciaires - Canadian Drug Policy Coalition","og_description":"Depuis le 2 septembre 2025, l&#8217;arm\u00e9e am\u00e9ricaine a tu\u00e9 au moins 57 civils dans les eaux internationales, lors de frappes que le droit international et les autorit\u00e9s charg\u00e9es des droits de l&#8217;homme ont condamn\u00e9es comme \u00e9tant ill\u00e9gales.1 Des preuves de plus en plus nombreuses d\u00e9montrent l&#8217;implication importante du Canada dans ces op\u00e9rations militaires men\u00e9es par [&hellip;]","og_url":"https:\/\/www.drugpolicy.ca\/fr\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/","og_site_name":"Canadian Drug Policy Coalition","article_published_time":"2026-01-28T16:11:32+00:00","article_modified_time":"2026-02-02T18:41:33+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/drugpolicy.ca\/wp-content\/uploads\/2026\/01\/blog-post-template.png","type":"image\/png"}],"author":"Canadian Drug Policy Coalition","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Canadian Drug Policy Coalition","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.drugpolicy.ca\/fr\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/#article","isPartOf":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/"},"author":{"name":"Canadian Drug Policy Coalition","@id":"https:\/\/mail.canadiandrugpolicy.ca\/#\/schema\/person\/c32110f234bdb1f5d978710b6b406a30"},"headline":"Complicit\u00e9 du Canada avec les frappes militaires ill\u00e9gales des \u00c9tats-Unis : Quand la politique de sant\u00e9 publique en mati\u00e8re de drogues rencontre les ex\u00e9cutions extrajudiciaires","datePublished":"2026-01-28T16:11:32+00:00","dateModified":"2026-02-02T18:41:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/"},"wordCount":2734,"publisher":{"@id":"https:\/\/mail.canadiandrugpolicy.ca\/#organization"},"image":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/#primaryimage"},"thumbnailUrl":"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2026\/01\/blog-post-template.png","articleSection":["International","Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.drugpolicy.ca\/fr\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/","url":"https:\/\/www.drugpolicy.ca\/fr\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/","name":"Complicit\u00e9 du Canada avec les frappes militaires ill\u00e9gales des \u00c9tats-Unis : Quand la politique de sant\u00e9 publique en mati\u00e8re de drogues rencontre les ex\u00e9cutions extrajudiciaires - Canadian Drug Policy Coalition","isPartOf":{"@id":"https:\/\/mail.canadiandrugpolicy.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/#primaryimage"},"image":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/#primaryimage"},"thumbnailUrl":"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2026\/01\/blog-post-template.png","datePublished":"2026-01-28T16:11:32+00:00","dateModified":"2026-02-02T18:41:33+00:00","breadcrumb":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.drugpolicy.ca\/fr\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.drugpolicy.ca\/fr\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/#primaryimage","url":"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2026\/01\/blog-post-template.png","contentUrl":"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2026\/01\/blog-post-template.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.drugpolicy.ca\/fr\/complicite-du-canada-avec-les-frappes-militaires-illegales-des-etats-unis-quand-la-politique-de-sante-publique-en-matiere-de-drogues-rencontre-les-executions-extrajudiciaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/drugpolicy.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Complicit\u00e9 du Canada avec les frappes militaires ill\u00e9gales des \u00c9tats-Unis : Quand la politique de sant\u00e9 publique en mati\u00e8re de drogues rencontre les ex\u00e9cutions extrajudiciaires"}]},{"@type":"WebSite","@id":"https:\/\/mail.canadiandrugpolicy.ca\/#website","url":"https:\/\/mail.canadiandrugpolicy.ca\/","name":"Canadian Drug Policy Coalition","description":"Change policy. Save lives.","publisher":{"@id":"https:\/\/mail.canadiandrugpolicy.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.canadiandrugpolicy.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mail.canadiandrugpolicy.ca\/#organization","name":"Canadian Drug Policy Coalition","url":"https:\/\/mail.canadiandrugpolicy.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mail.canadiandrugpolicy.ca\/#\/schema\/logo\/image\/","url":"https:\/\/drugpolicy.ca\/wp-content\/uploads\/2019\/04\/CDPC-logo-white-on-red-150-dpi.jpg","contentUrl":"https:\/\/drugpolicy.ca\/wp-content\/uploads\/2019\/04\/CDPC-logo-white-on-red-150-dpi.jpg","width":332,"height":333,"caption":"Canadian Drug Policy Coalition"},"image":{"@id":"https:\/\/mail.canadiandrugpolicy.ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mail.canadiandrugpolicy.ca\/#\/schema\/person\/c32110f234bdb1f5d978710b6b406a30","name":"Canadian Drug Policy Coalition","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g","caption":"Canadian Drug Policy Coalition"},"description":"Advocating for public health- and human rights-based drug policy grounded in evidence, compassion, and social justice","url":"https:\/\/www.drugpolicy.ca\/fr\/author\/canadian-drug-policy-coalition\/"}]}},"mfb_rest_fields":["title","yoast_head","yoast_head_json"],"_links":{"self":[{"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/posts\/22256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/comments?post=22256"}],"version-history":[{"count":2,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/posts\/22256\/revisions"}],"predecessor-version":[{"id":22258,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/posts\/22256\/revisions\/22258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/media\/22268"}],"wp:attachment":[{"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/media?parent=22256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/categories?post=22256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/tags?post=22256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}