{"id":13360,"date":"2019-10-27T17:50:19","date_gmt":"2019-10-28T01:50:19","guid":{"rendered":"https:\/\/drugpolicy.ca\/?p=13360"},"modified":"2020-11-09T17:52:02","modified_gmt":"2020-11-10T01:52:02","slug":"donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler","status":"publish","type":"post","link":"https:\/\/www.drugpolicy.ca\/fr\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\/","title":{"rendered":"Donald MacPherson, directeur ex\u00e9cutif de la Coalition canadienne des politiques sur les drogues, re\u00e7oit un doctorat honorifique de l&#8217;Universit\u00e9 Adler"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\"><em><em>Ce prix est le tout premier doctorat honorifique de l&#8217;universit\u00e9 au Canada et reconna\u00eet que la crise des surdoses et de l&#8217;empoisonnement par la drogue est un probl\u00e8me critique de notre \u00e9poque en mati\u00e8re de droits de l&#8217;homme et de justice sociale<\/em><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">VANCOUVER, C.-B.\u2014 Donald MacPherson, directeur ex\u00e9cutif de la Coalition canadienne des politiques sur les drogues et auteur de l&#8217;ouvrage fondamental <em>Four Pillars Drug Strategy<\/em>, a re\u00e7u aujourd&#8217;hui le tout premier doctorat honorifique de l&#8217;Universit\u00e9 Adler au Canada. L&#8217;universit\u00e9 a choisi MacPherson pour son r\u00f4le de pionnier dans la r\u00e9forme de la politique sur les drogues, dans la d\u00e9fense et la promotion des droits de l&#8217;homme et de l&#8217;inclusion sociale des personnes qui consomment des substances.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Donald MacPherson est exemplaire du travail pour la justice sociale que nous menons \u00e0 l&#8217;Universit\u00e9 Adler \u00bb, a d\u00e9clar\u00e9 Joy MacPhail, pr\u00e9sidente du conseil d&#8217;administration de l&#8217;Universit\u00e9 Adler. \u00ab Ses efforts novateurs visent \u00e0 am\u00e9liorer la sant\u00e9 et la s\u00e9curit\u00e9 publiques en r\u00e9formant les politiques en mati\u00e8re de drogue et en promouvant les droits humains des personnes qui consomment des substances. Son travail nous rappelle combien il reste \u00e0 faire pour r\u00e9soudre la crise des surdoses et nous esp\u00e9rons que nos dipl\u00f4m\u00e9s seront inspir\u00e9s par le d\u00e9vouement de MacPherson pour faire progresser la justice sociale tout au long de leurs carri\u00e8res \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce prix est \u00e9galement une reconnaissance de la perte tragique de vies humaines caus\u00e9e par le march\u00e9 illicite et non r\u00e9glement\u00e9 de la drogue\u2014cons\u00e9quence de nos politiques inad\u00e9quates en mati\u00e8re de drogue\u2014qui constitue un probl\u00e8me crucial pour les droits de l&#8217;homme et la justice sociale de notre \u00e9poque. \u00ab Je suis honor\u00e9 de recevoir ce prix de l&#8217;universit\u00e9 Adler et cette reconnaissance du fait que le travail visant \u00e0 changer les politiques publiques archa\u00efques et n\u00e9fastes est l&#8217;un des d\u00e9fis de notre temps \u00bb, a d\u00e9clar\u00e9 M. MacPherson. \u00ab Nous vivons une p\u00e9riode caract\u00e9ris\u00e9e par un \u00e9chec catastrophique de la mani\u00e8re dont nous traitons les personnes qui consomment des drogues criminalis\u00e9es. Nos syst\u00e8mes sont gravement d\u00e9ficients et doivent \u00eatre remplac\u00e9s \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au Canada de 2016 \u00e0 mars 2019, il y a eu <strong>12 813 <\/strong>morts li\u00e9es aux opio\u00efdes. L&#8217;esp\u00e9rance de vie n&#8217;a pas augment\u00e9 pour la premi\u00e8re fois depuis plus de quatre d\u00e9cennies. En Colombie-Britannique, les surdoses sont aujourd&#8217;hui la principale cause de morts non naturelles, d\u00e9passant ainsi le nombre de d\u00e9c\u00e8s accidentels par homicide, suicide et accident de voiture tous ensemble. Les provinces de l&#8217;Alberta et de l&#8217;Ontario ont \u00e9galement \u00e9t\u00e9 particuli\u00e8rement touch\u00e9es, puisque la province de l&#8217;Ontario a connu l&#8217;ann\u00e9e derni\u00e8re un record de d\u00e9c\u00e8s par surdose.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p style=\"font-size:2.0em; line-height:40px; color:#cc0633\">\u00ab Nous vivons une \u00e9poque caract\u00e9ris\u00e9e par un \u00e9chec catastrophique dans la mani\u00e8re dont nous abordons les personnes qui consomment des drogues criminalis\u00e9es. Nos syst\u00e8mes sont gravement d\u00e9ficients et doivent \u00eatre remplac\u00e9s. \u00bb<\/p><\/blockquote>\n\n\n<p style=\"color: #cc0633; text-align: right; margin-top: -10px; font-family: faustina;\">~Donald MacPherson, Coalition canadienne des politiques sur les drogues<\/p>\n\n\n<p class=\"wp-block-paragraph\">MacPherson a \u00e9t\u00e9 conf\u00e9rencier invit\u00e9 pour le programme de politique publique et d&#8217;administration de l&#8217;Universit\u00e9 Adler. Tous les programmes menant \u00e0 un dipl\u00f4me d&#8217;\u00e9tudes sup\u00e9rieures \u00e0 l&#8217;Universit\u00e9 Adler sont fortement ancr\u00e9s dans les principes de justice sociale et offrent aux \u00e9tudiants des exp\u00e9riences d&#8217;apprentissage pratiques avec plus de 200 organisations communautaires participantes. De nombreux \u00e9tudiants travaillent dans des organisations qui s&#8217;occupent de la crise de surdose, en fournissant des services de sant\u00e9 mentale ainsi que d&#8217;autres services.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">MacPherson est \u00e9galement professeur adjoint \u00e0 la facult\u00e9 des sciences de la sant\u00e9 \u00e0 l&#8217;universit\u00e9 Simon Fraser, dont la Coalition canadienne des politiques sur les drogues fait partie, ainsi que co-auteur de <em>Raise Shit ! Social Action Saving Lives <\/em>(2009) et <em>More Harm than Good : Drug Policy in Canada <\/em>(2016). Il est engag\u00e9 dans le travail sur la politique des drogues au niveau local, national et international et il a \u00e9t\u00e9 le premier coordinateur des politiques sur les drogues en Am\u00e9rique du Nord \u00e0 la Ville de Vancouver o\u00f9 il a travaill\u00e9 pendant 22 ans. Sa biographie compl\u00e8te est disponible <a href=\"https:\/\/drugpolicy.ca\/fr\/about\/our-staff\/\" target=\"_blank\" rel=\"noreferrer noopener\">ici<\/a>.<\/p>\n\n\n\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#cc0633\"><strong>Contact<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Peter Kim<br>Responsable de la communication strat\u00e9gique<br>Coalition canadienne des politiques sur les drogues<br><a href=\"mailto:peter_k@sfu.ca\">peter_k@sfu.ca<\/a><br>604-787-4043<\/p>\n\n\n<p style=\"text-align: center; border: 3px solid #c21718; background-color: #ffd1d5; padding-top: 5px; padding-bottom: 5px;\"><a href=\"https:\/\/drugpolicy.ca\/wp-content\/uploads\/2020\/11\/FR-CDPC-Release-Degree-Oct-27.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>T\u00e9l\u00e9charger PDF<\/strong><\/a><\/p>\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u2013 30 \u2013<\/p>\n\n\n\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#cc0633\"><strong><strong>\u00c0 propos de la Coalition canadienne des politiques sur les drogues<\/strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Coalition canadienne des politiques sur les drogues (CCPD) est une coalition de 70 organisations et de 3 000 individus travaillant \u00e0 soutenir le d\u00e9veloppement d&#8217;une politique progressive en mati\u00e8re de drogues, fond\u00e9e sur la science, guid\u00e9e par des principes de sant\u00e9 publique et respectueuse des droits de l&#8217;homme. La CCPD fonctionne au sein de l&#8217;universit\u00e9 Simon Fraser, dans le Centre de recherche appliqu\u00e9e en sant\u00e9 mentale et en toxicomanie. Le CCPD vise \u00e0 inclure les personnes qui consomment des drogues et celles qui sont victimes de la lutte contre la drogue dans le mouvement vers une soci\u00e9t\u00e9 canadienne plus saine, sans stigmatisation et sans exclusion sociale. <a href=\"https:www.drugpolicy.ca\/fr\" target=\"_blank\" rel=\"noreferrer noopener\">www.drugpolicy.ca\/fr\/<\/a><\/p>\n\n\n\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#cc0633\"><strong><strong>\u00c0 propos de l&#8217;Universit\u00e9 Adler<\/strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;Universit\u00e9 Adler s&#8217;est engag\u00e9e \u00e0 am\u00e9liorer la sant\u00e9 et le bien-\u00eatre des individus et des communaut\u00e9s \u00e0 travers une \u00e9volution sociale positive. Situ\u00e9e au c\u0153ur du centre-ville de Vancouver, l&#8217;universit\u00e9 Adler est un \u00e9tablissement ind\u00e9pendant d&#8217;enseignement sup\u00e9rieur \u00e0 but non lucratif. L&#8217;universit\u00e9 offre des programmes d&#8217;\u00e9tudes sup\u00e9rieures en psychologie, en counseling et en politique publique. Fond\u00e9e en 1952, l&#8217;universit\u00e9 Adler a des campus \u00e0 Vancouver, \u00e0 Chicago et en ligne. Sa mission est de poursuivre le travail r\u00e9volutionnaire d&#8217;Alfred Adler, le premier psychologue communautaire, en dipl\u00f4mant des professionnels socialement responsables, en engageant les communaut\u00e9s et en promouvant la justice sociale. <a href=\"https:\/\/www.adler.edu\" target=\"_blank\" rel=\"noreferrer noopener\">www.adler.edu<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce prix est le tout premier doctorat honorifique de l&#8217;universit\u00e9 au Canada et reconna\u00eet que la crise des surdoses et de l&#8217;empoisonnement par la drogue est un probl\u00e8me critique de notre \u00e9poque en mati\u00e8re de droits de l&#8217;homme et de justice sociale<\/p>\n","protected":false},"author":38,"featured_media":8068,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","footnotes":""},"categories":[1118],"tags":[],"class_list":["post-13360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communique-de-presse"],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Donald MacPherson, directeur ex\u00e9cutif de la Coalition canadienne des politiques sur les drogues, re\u00e7oit un doctorat honorifique de l&#039;Universit\u00e9 Adler - Canadian Drug Policy Coalition<\/title>\n<meta name=\"description\" content=\"Ce prix est le tout premier doctorat honorifique de l&#039;universit\u00e9 au Canada et reconna\u00eet que la crise des surdoses et de l&#039;empoisonnement par la drogue est un probl\u00e8me critique de notre \u00e9poque en mati\u00e8re de droits de l&#039;homme et de justice sociale\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.drugpolicy.ca\/fr\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Donald MacPherson, directeur ex\u00e9cutif de la Coalition canadienne des politiques sur les drogues, re\u00e7oit un doctorat honorifique de l&#039;Universit\u00e9 Adler - Canadian Drug Policy Coalition\" \/>\n<meta property=\"og:description\" content=\"Ce prix est le tout premier doctorat honorifique de l&#039;universit\u00e9 au Canada et reconna\u00eet que la crise des surdoses et de l&#039;empoisonnement par la drogue est un probl\u00e8me critique de notre \u00e9poque en mati\u00e8re de droits de l&#039;homme et de justice sociale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.drugpolicy.ca\/fr\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\/\" \/>\n<meta property=\"og:site_name\" content=\"Canadian Drug Policy Coalition\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-28T01:50:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-10T01:52:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2019\/12\/2019-10-27-11.44.16_JW21416-\u00a9Jerald-Walliser.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Canadian Drug Policy Coalition\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canadian Drug Policy Coalition\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\\\/\"},\"author\":{\"name\":\"Canadian Drug Policy Coalition\",\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#\\\/schema\\\/person\\\/c32110f234bdb1f5d978710b6b406a30\"},\"headline\":\"Donald MacPherson, directeur ex\u00e9cutif de la Coalition canadienne des politiques sur les drogues, re\u00e7oit un doctorat honorifique de l&#8217;Universit\u00e9 Adler\",\"datePublished\":\"2019-10-28T01:50:19+00:00\",\"dateModified\":\"2020-11-10T01:52:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\\\/\"},\"wordCount\":1015,\"publisher\":{\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.drugpolicy.ca\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/2019-10-27-11.44.16_JW21416-\u00a9Jerald-Walliser.jpg\",\"articleSection\":[\"communiqu\u00e9 de presse\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\\\/\",\"url\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\\\/\",\"name\":\"Donald MacPherson, directeur ex\u00e9cutif de la Coalition canadienne des politiques sur les drogues, re\u00e7oit un doctorat honorifique de l'Universit\u00e9 Adler - Canadian Drug Policy Coalition\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.drugpolicy.ca\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/2019-10-27-11.44.16_JW21416-\u00a9Jerald-Walliser.jpg\",\"datePublished\":\"2019-10-28T01:50:19+00:00\",\"dateModified\":\"2020-11-10T01:52:02+00:00\",\"description\":\"Ce prix est le tout premier doctorat honorifique de l'universit\u00e9 au Canada et reconna\u00eet que la crise des surdoses et de l'empoisonnement par la drogue est un probl\u00e8me critique de notre \u00e9poque en mati\u00e8re de droits de l'homme et de justice sociale\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.drugpolicy.ca\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/2019-10-27-11.44.16_JW21416-\u00a9Jerald-Walliser.jpg\",\"contentUrl\":\"https:\\\/\\\/www.drugpolicy.ca\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/2019-10-27-11.44.16_JW21416-\u00a9Jerald-Walliser.jpg\",\"width\":1280,\"height\":1024,\"caption\":\"Photo credit: Jerald Walliser\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/drugpolicy.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Donald MacPherson, directeur ex\u00e9cutif de la Coalition canadienne des politiques sur les drogues, re\u00e7oit un doctorat honorifique de l&#8217;Universit\u00e9 Adler\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#website\",\"url\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/\",\"name\":\"Canadian Drug Policy Coalition\",\"description\":\"Change policy. Save lives.\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#organization\",\"name\":\"Canadian Drug Policy Coalition\",\"url\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/drugpolicy.ca\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/CDPC-logo-white-on-red-150-dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/drugpolicy.ca\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/CDPC-logo-white-on-red-150-dpi.jpg\",\"width\":332,\"height\":333,\"caption\":\"Canadian Drug Policy Coalition\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#\\\/schema\\\/person\\\/c32110f234bdb1f5d978710b6b406a30\",\"name\":\"Canadian Drug Policy Coalition\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g\",\"caption\":\"Canadian Drug Policy Coalition\"},\"description\":\"Advocating for public health- and human rights-based drug policy grounded in evidence, compassion, and social justice\",\"url\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/author\\\/canadian-drug-policy-coalition\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Donald MacPherson, directeur ex\u00e9cutif de la Coalition canadienne des politiques sur les drogues, re\u00e7oit un doctorat honorifique de l'Universit\u00e9 Adler - Canadian Drug Policy Coalition","description":"Ce prix est le tout premier doctorat honorifique de l'universit\u00e9 au Canada et reconna\u00eet que la crise des surdoses et de l'empoisonnement par la drogue est un probl\u00e8me critique de notre \u00e9poque en mati\u00e8re de droits de l'homme et de justice sociale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.drugpolicy.ca\/fr\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\/","og_locale":"fr_FR","og_type":"article","og_title":"Donald MacPherson, directeur ex\u00e9cutif de la Coalition canadienne des politiques sur les drogues, re\u00e7oit un doctorat honorifique de l'Universit\u00e9 Adler - Canadian Drug Policy Coalition","og_description":"Ce prix est le tout premier doctorat honorifique de l'universit\u00e9 au Canada et reconna\u00eet que la crise des surdoses et de l'empoisonnement par la drogue est un probl\u00e8me critique de notre \u00e9poque en mati\u00e8re de droits de l'homme et de justice sociale","og_url":"https:\/\/www.drugpolicy.ca\/fr\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\/","og_site_name":"Canadian Drug Policy Coalition","article_published_time":"2019-10-28T01:50:19+00:00","article_modified_time":"2020-11-10T01:52:02+00:00","og_image":[{"width":1280,"height":1024,"url":"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2019\/12\/2019-10-27-11.44.16_JW21416-\u00a9Jerald-Walliser.jpg","type":"image\/jpeg"}],"author":"Canadian Drug Policy Coalition","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Canadian Drug Policy Coalition","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.drugpolicy.ca\/fr\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\/#article","isPartOf":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\/"},"author":{"name":"Canadian Drug Policy Coalition","@id":"https:\/\/mail.canadiandrugpolicy.ca\/#\/schema\/person\/c32110f234bdb1f5d978710b6b406a30"},"headline":"Donald MacPherson, directeur ex\u00e9cutif de la Coalition canadienne des politiques sur les drogues, re\u00e7oit un doctorat honorifique de l&#8217;Universit\u00e9 Adler","datePublished":"2019-10-28T01:50:19+00:00","dateModified":"2020-11-10T01:52:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\/"},"wordCount":1015,"publisher":{"@id":"https:\/\/mail.canadiandrugpolicy.ca\/#organization"},"image":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\/#primaryimage"},"thumbnailUrl":"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2019\/12\/2019-10-27-11.44.16_JW21416-\u00a9Jerald-Walliser.jpg","articleSection":["communiqu\u00e9 de presse"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.drugpolicy.ca\/fr\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\/","url":"https:\/\/www.drugpolicy.ca\/fr\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\/","name":"Donald MacPherson, directeur ex\u00e9cutif de la Coalition canadienne des politiques sur les drogues, re\u00e7oit un doctorat honorifique de l'Universit\u00e9 Adler - Canadian Drug Policy Coalition","isPartOf":{"@id":"https:\/\/mail.canadiandrugpolicy.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\/#primaryimage"},"image":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\/#primaryimage"},"thumbnailUrl":"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2019\/12\/2019-10-27-11.44.16_JW21416-\u00a9Jerald-Walliser.jpg","datePublished":"2019-10-28T01:50:19+00:00","dateModified":"2020-11-10T01:52:02+00:00","description":"Ce prix est le tout premier doctorat honorifique de l'universit\u00e9 au Canada et reconna\u00eet que la crise des surdoses et de l'empoisonnement par la drogue est un probl\u00e8me critique de notre \u00e9poque en mati\u00e8re de droits de l'homme et de justice sociale","breadcrumb":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.drugpolicy.ca\/fr\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.drugpolicy.ca\/fr\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\/#primaryimage","url":"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2019\/12\/2019-10-27-11.44.16_JW21416-\u00a9Jerald-Walliser.jpg","contentUrl":"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2019\/12\/2019-10-27-11.44.16_JW21416-\u00a9Jerald-Walliser.jpg","width":1280,"height":1024,"caption":"Photo credit: Jerald Walliser"},{"@type":"BreadcrumbList","@id":"https:\/\/www.drugpolicy.ca\/fr\/donald-macpherson-directeur-executif-de-la-coalition-canadienne-des-politiques-sur-les-drogues-recoit-un-doctorat-honorifique-de-luniversite-adler\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/drugpolicy.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Donald MacPherson, directeur ex\u00e9cutif de la Coalition canadienne des politiques sur les drogues, re\u00e7oit un doctorat honorifique de l&#8217;Universit\u00e9 Adler"}]},{"@type":"WebSite","@id":"https:\/\/mail.canadiandrugpolicy.ca\/#website","url":"https:\/\/mail.canadiandrugpolicy.ca\/","name":"Canadian Drug Policy Coalition","description":"Change policy. Save lives.","publisher":{"@id":"https:\/\/mail.canadiandrugpolicy.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.canadiandrugpolicy.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mail.canadiandrugpolicy.ca\/#organization","name":"Canadian Drug Policy Coalition","url":"https:\/\/mail.canadiandrugpolicy.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mail.canadiandrugpolicy.ca\/#\/schema\/logo\/image\/","url":"https:\/\/drugpolicy.ca\/wp-content\/uploads\/2019\/04\/CDPC-logo-white-on-red-150-dpi.jpg","contentUrl":"https:\/\/drugpolicy.ca\/wp-content\/uploads\/2019\/04\/CDPC-logo-white-on-red-150-dpi.jpg","width":332,"height":333,"caption":"Canadian Drug Policy Coalition"},"image":{"@id":"https:\/\/mail.canadiandrugpolicy.ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mail.canadiandrugpolicy.ca\/#\/schema\/person\/c32110f234bdb1f5d978710b6b406a30","name":"Canadian Drug Policy Coalition","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g","caption":"Canadian Drug Policy Coalition"},"description":"Advocating for public health- and human rights-based drug policy grounded in evidence, compassion, and social justice","url":"https:\/\/www.drugpolicy.ca\/fr\/author\/canadian-drug-policy-coalition\/"}]}},"mfb_rest_fields":["title","yoast_head","yoast_head_json"],"_links":{"self":[{"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/posts\/13360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/comments?post=13360"}],"version-history":[{"count":26,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/posts\/13360\/revisions"}],"predecessor-version":[{"id":13389,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/posts\/13360\/revisions\/13389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/media\/8068"}],"wp:attachment":[{"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/media?parent=13360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/categories?post=13360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/tags?post=13360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}