{"id":13326,"date":"2019-11-25T14:27:29","date_gmt":"2019-11-25T22:27:29","guid":{"rendered":"https:\/\/drugpolicy.ca\/?p=13326"},"modified":"2020-11-09T14:39:44","modified_gmt":"2020-11-09T22:39:44","slug":"la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv","status":"publish","type":"post","link":"https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/","title":{"rendered":"La Coalition canadienne des politiques sur les drogues applaudit l&#8217;adoption d&#8217;une r\u00e9solution lors de la convention annuelle du NPD de C.-B. qui soutient la d\u00e9criminalisation des drogues et un approvisionnement s\u00e9curitaire des opio\u00efdes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">VANCOUVER, C.-B.\u2014 Ce week-end, lors du congr\u00e8s annuel du NPD \u00e0 Victoria, les membres ont adopt\u00e9 unanimement une r\u00e9solution importante exigeant la d\u00e9criminalisation de la possession personnelle de drogues et un plus grand financement et appui \u00e0 la distribution de formes l\u00e9gales et s\u00e9curitaires d&#8217;opio\u00efdes. Il s&#8217;agit d&#8217;une d\u00e9claration importante et sans pr\u00e9c\u00e9dent faite par les membres du NPD provincial, soulignant le besoin urgent d&#8217;agir pour sauver des vies dans toute la province.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab C&#8217;est une bonne nouvelle et cela montre que les membres du NPD sont tr\u00e8s conscients des mesures \u00e0 prendre \u00bb, a d\u00e9clar\u00e9 Donald MacPherson, directeur ex\u00e9cutif de la Coalition canadienne des politiques sur les drogues. \u00ab Notre question est donc maintenant : quand verrons-nous des actions sur ces probl\u00e8mes? \u00bb<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p style=\"font-size:2.0em; line-height:40px; color:#cc0633\">\u00ab Chaque jour, quatre personnes continuent de mourir en Colombie-Britannique \u00e0 cause de la distribution de drogues toxiques, et il faut agir maintenant. \u00bb<\/p><\/blockquote>\n\n\n<p style=\"color: #cc0633; text-align: right; margin-top: -10px; font-family: faustina;\">~Donald MacPherson, Coalition canadienne des politiques sur les drogues<\/p>\n\n\n<p class=\"wp-block-paragraph\">La r\u00e9solution augmente la pression sur le gouvernement provincial pour qu&#8217;il agisse imm\u00e9diatement et apporte les r\u00e9formes n\u00e9cessaires pour sauver des vies, \u00e0 la mani\u00e8re des lib\u00e9raux de la C.-B. qui ont d\u00e9clar\u00e9 une urgence de sant\u00e9 publique en 2016, permettant l&#8217;ouverture de sites de pr\u00e9vention de surdose dans toute la province.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La requ\u00eate a \u00e9t\u00e9 pr\u00e9sent\u00e9e par au moins dix associations de circonscription et syndicats qui demandent des changements vitaux aux lois en mati\u00e8re de drogues qui criminalisent \u00e0 pr\u00e9sent la consommation de substances et les personnes qui en consomment \u2014 ce qui contribue au nombre catastrophique de morts en Colombie- Britannique et au Canada en g\u00e9n\u00e9ral. Au mois de juin dernier, la Coalition canadienne des politiques sur les drogues, ainsi que des organisations alli\u00e9es,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ont pouss\u00e9 le gouvernement \u00e0 modifier la loi sur la police afin de d\u00e9criminaliser la possession personnelle de drogues. Des appels similaires ont \u00e9t\u00e9 lanc\u00e9s par les autorit\u00e9s de sant\u00e9 de la province, notamment par le Dr Bonnie Henry qui, dans un long rapport (version anglaise), a soulign\u00e9 l&#8217;urgence de la d\u00e9criminalisation. \u00ab Le r\u00e9gime de r\u00e9glementation actuel de la politique des drogues bas\u00e9e sur la prohibition et la criminalisation ne fait pas grand- chose pour traiter les m\u00e9faits li\u00e9s \u00e0 la consommation de substances, mais soutient plut\u00f4t une augmentation des m\u00e9faits sociaux et sanitaires, une augmentation de la puissance des drogues ill\u00e9gales, ainsi qu&#8217;une augmentation de l&#8217;utilisation dangereuse des drogues, de la stigmatisation, de la honte et de la discrimination \u00bb, a-t-elle \u00e9crit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous sommes satisfaits de cet engagement affirm\u00e9 de passer \u00e0 une approche des politiques sur les drogues qui soit fond\u00e9e sur la sant\u00e9 publique et sur les preuves et de se d\u00e9tourner d&#8217;une approche punitive de la criminalit\u00e9. Par ailleurs, on esp\u00e8re que le gouvernement provincial \u00e9coutera les souhaits de ses membres quant \u00e0 cette question, lesquels ont \u00e9t\u00e9 exprim\u00e9s sans \u00e9quivoque ce week-end.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depuis 2016, 4375 personnes sont mortes de causes li\u00e9es aux opio\u00efdes en Colombie-Britannique.<\/p>\n\n\n\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#c31424\"><strong>Contact<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Peter Kim<br>Responsable de la communication strat\u00e9gique<br>Coalition canadienne des politiques sur les drogues<br><a href=\"mailto:peter_k@sfu.ca\">peter_k@sfu.ca<\/a><strong><br><\/strong>778-782-8217<\/p>\n\n\n<p style=\"text-align: center; border: 3px solid #c21718; background-color: #ffd1d5; padding-top: 5px; padding-bottom: 5px;\"><a href=\"https:\/\/drugpolicy.ca\/wp-content\/uploads\/2020\/11\/FRCDPC-Press-Release-NDP-Resolution-Nov-25.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>T\u00e9l\u00e9charger<\/strong><\/a><\/p>\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">\u2013 30 \u2013<\/p>\n\n\n\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#c31424\"><strong><strong>\u00c0 propos de la Coalition canadienne des politiques sur les drogues<\/strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Coalition canadienne des politiques sur les drogues (CCPD) est une coalition de 70 organisations et de 3 000 individus travaillant \u00e0 soutenir le d\u00e9veloppement d&#8217;une politique progressive en mati\u00e8re de drogues, fond\u00e9e sur la science, guid\u00e9e par des principes de sant\u00e9 publique et respectueuse des droits de l&#8217;homme. La CCPD fonctionne au sein de l&#8217;universit\u00e9 Simon Fraser, dans le Centre de recherche appliqu\u00e9e en sant\u00e9 mentale et en toxicomanie. Le CCPD vise \u00e0 inclure les personnes qui consomment des drogues et celles qui sont victimes de la lutte contre la drogue dans le mouvement vers une soci\u00e9t\u00e9 canadienne plus saine, sans stigmatisation et sans exclusion sociale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chaque jour, quatre personnes continuent de mourir en Colombie-Britannique \u00e0 cause de la distribution de drogues toxiques, et il faut agir maintenant.<\/p>\n","protected":false},"author":38,"featured_media":7983,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","footnotes":""},"categories":[1118],"tags":[],"class_list":["post-13326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communique-de-presse"],"acf":[],"mb":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Coalition canadienne des politiques sur les drogues applaudit l&#039;adoption d&#039;une r\u00e9solution lors de la convention annuelle du NPD de C.-B. qui soutient la d\u00e9criminalisation des drogues et un approvisionnement s\u00e9curitaire des opio\u00efdes - Canadian Drug Policy Coalition<\/title>\n<meta name=\"description\" content=\"Chaque jour, quatre personnes continuent de mourir en Colombie-Britannique \u00e0 cause de la distribution de drogues toxiques, et il faut agir maintenant.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Coalition canadienne des politiques sur les drogues applaudit l&#039;adoption d&#039;une r\u00e9solution lors de la convention annuelle du NPD de C.-B. qui soutient la d\u00e9criminalisation des drogues et un approvisionnement s\u00e9curitaire des opio\u00efdes - Canadian Drug Policy Coalition\" \/>\n<meta property=\"og:description\" content=\"Chaque jour, quatre personnes continuent de mourir en Colombie-Britannique \u00e0 cause de la distribution de drogues toxiques, et il faut agir maintenant.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/\" \/>\n<meta property=\"og:site_name\" content=\"Canadian Drug Policy Coalition\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-25T22:27:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-09T22:39:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2019\/11\/b-c-ndp-photo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"804\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Canadian Drug Policy Coalition\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canadian Drug Policy Coalition\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\\\/\"},\"author\":{\"name\":\"Canadian Drug Policy Coalition\",\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#\\\/schema\\\/person\\\/c32110f234bdb1f5d978710b6b406a30\"},\"headline\":\"La Coalition canadienne des politiques sur les drogues applaudit l&#8217;adoption d&#8217;une r\u00e9solution lors de la convention annuelle du NPD de C.-B. qui soutient la d\u00e9criminalisation des drogues et un approvisionnement s\u00e9curitaire des opio\u00efdes\",\"datePublished\":\"2019-11-25T22:27:29+00:00\",\"dateModified\":\"2020-11-09T22:39:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\\\/\"},\"wordCount\":705,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.drugpolicy.ca\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/b-c-ndp-photo.jpg\",\"articleSection\":[\"communiqu\u00e9 de presse\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\\\/\",\"url\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\\\/\",\"name\":\"La Coalition canadienne des politiques sur les drogues applaudit l'adoption d'une r\u00e9solution lors de la convention annuelle du NPD de C.-B. qui soutient la d\u00e9criminalisation des drogues et un approvisionnement s\u00e9curitaire des opio\u00efdes - Canadian Drug Policy Coalition\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.drugpolicy.ca\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/b-c-ndp-photo.jpg\",\"datePublished\":\"2019-11-25T22:27:29+00:00\",\"dateModified\":\"2020-11-09T22:39:44+00:00\",\"description\":\"Chaque jour, quatre personnes continuent de mourir en Colombie-Britannique \u00e0 cause de la distribution de drogues toxiques, et il faut agir maintenant.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.drugpolicy.ca\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/b-c-ndp-photo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.drugpolicy.ca\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/b-c-ndp-photo.jpg\",\"width\":804,\"height\":534,\"caption\":\"(Photo credit: Canadian Press)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/drugpolicy.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Coalition canadienne des politiques sur les drogues applaudit l&#8217;adoption d&#8217;une r\u00e9solution lors de la convention annuelle du NPD de C.-B. qui soutient la d\u00e9criminalisation des drogues et un approvisionnement s\u00e9curitaire des opio\u00efdes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#website\",\"url\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/\",\"name\":\"Canadian Drug Policy Coalition\",\"description\":\"Change policy. Save lives.\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#organization\",\"name\":\"Canadian Drug Policy Coalition\",\"url\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/drugpolicy.ca\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/CDPC-logo-white-on-red-150-dpi.jpg\",\"contentUrl\":\"https:\\\/\\\/drugpolicy.ca\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/CDPC-logo-white-on-red-150-dpi.jpg\",\"width\":332,\"height\":333,\"caption\":\"Canadian Drug Policy Coalition\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mail.canadiandrugpolicy.ca\\\/#\\\/schema\\\/person\\\/c32110f234bdb1f5d978710b6b406a30\",\"name\":\"Canadian Drug Policy Coalition\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g\",\"caption\":\"Canadian Drug Policy Coalition\"},\"description\":\"Advocating for public health- and human rights-based drug policy grounded in evidence, compassion, and social justice\",\"url\":\"https:\\\/\\\/www.drugpolicy.ca\\\/fr\\\/author\\\/canadian-drug-policy-coalition\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Coalition canadienne des politiques sur les drogues applaudit l'adoption d'une r\u00e9solution lors de la convention annuelle du NPD de C.-B. qui soutient la d\u00e9criminalisation des drogues et un approvisionnement s\u00e9curitaire des opio\u00efdes - Canadian Drug Policy Coalition","description":"Chaque jour, quatre personnes continuent de mourir en Colombie-Britannique \u00e0 cause de la distribution de drogues toxiques, et il faut agir maintenant.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/","og_locale":"fr_FR","og_type":"article","og_title":"La Coalition canadienne des politiques sur les drogues applaudit l'adoption d'une r\u00e9solution lors de la convention annuelle du NPD de C.-B. qui soutient la d\u00e9criminalisation des drogues et un approvisionnement s\u00e9curitaire des opio\u00efdes - Canadian Drug Policy Coalition","og_description":"Chaque jour, quatre personnes continuent de mourir en Colombie-Britannique \u00e0 cause de la distribution de drogues toxiques, et il faut agir maintenant.","og_url":"https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/","og_site_name":"Canadian Drug Policy Coalition","article_published_time":"2019-11-25T22:27:29+00:00","article_modified_time":"2020-11-09T22:39:44+00:00","og_image":[{"width":804,"height":534,"url":"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2019\/11\/b-c-ndp-photo.jpg","type":"image\/jpeg"}],"author":"Canadian Drug Policy Coalition","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Canadian Drug Policy Coalition","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/#article","isPartOf":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/"},"author":{"name":"Canadian Drug Policy Coalition","@id":"https:\/\/mail.canadiandrugpolicy.ca\/#\/schema\/person\/c32110f234bdb1f5d978710b6b406a30"},"headline":"La Coalition canadienne des politiques sur les drogues applaudit l&#8217;adoption d&#8217;une r\u00e9solution lors de la convention annuelle du NPD de C.-B. qui soutient la d\u00e9criminalisation des drogues et un approvisionnement s\u00e9curitaire des opio\u00efdes","datePublished":"2019-11-25T22:27:29+00:00","dateModified":"2020-11-09T22:39:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/"},"wordCount":705,"commentCount":0,"publisher":{"@id":"https:\/\/mail.canadiandrugpolicy.ca\/#organization"},"image":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2019\/11\/b-c-ndp-photo.jpg","articleSection":["communiqu\u00e9 de presse"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/","url":"https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/","name":"La Coalition canadienne des politiques sur les drogues applaudit l'adoption d'une r\u00e9solution lors de la convention annuelle du NPD de C.-B. qui soutient la d\u00e9criminalisation des drogues et un approvisionnement s\u00e9curitaire des opio\u00efdes - Canadian Drug Policy Coalition","isPartOf":{"@id":"https:\/\/mail.canadiandrugpolicy.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/#primaryimage"},"image":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2019\/11\/b-c-ndp-photo.jpg","datePublished":"2019-11-25T22:27:29+00:00","dateModified":"2020-11-09T22:39:44+00:00","description":"Chaque jour, quatre personnes continuent de mourir en Colombie-Britannique \u00e0 cause de la distribution de drogues toxiques, et il faut agir maintenant.","breadcrumb":{"@id":"https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/#primaryimage","url":"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2019\/11\/b-c-ndp-photo.jpg","contentUrl":"https:\/\/www.drugpolicy.ca\/wp-content\/uploads\/2019\/11\/b-c-ndp-photo.jpg","width":804,"height":534,"caption":"(Photo credit: Canadian Press)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.drugpolicy.ca\/fr\/la-coalition-canadienne-des-politiques-sur-les-drogues-applaudit-ladoption-dune-resolution-lors-de-la-convention-annuelle-du-npd-de-c-b-qui-soutient-la-decriminalisation-des-drogues-et-un-approv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/drugpolicy.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"La Coalition canadienne des politiques sur les drogues applaudit l&#8217;adoption d&#8217;une r\u00e9solution lors de la convention annuelle du NPD de C.-B. qui soutient la d\u00e9criminalisation des drogues et un approvisionnement s\u00e9curitaire des opio\u00efdes"}]},{"@type":"WebSite","@id":"https:\/\/mail.canadiandrugpolicy.ca\/#website","url":"https:\/\/mail.canadiandrugpolicy.ca\/","name":"Canadian Drug Policy Coalition","description":"Change policy. Save lives.","publisher":{"@id":"https:\/\/mail.canadiandrugpolicy.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.canadiandrugpolicy.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mail.canadiandrugpolicy.ca\/#organization","name":"Canadian Drug Policy Coalition","url":"https:\/\/mail.canadiandrugpolicy.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mail.canadiandrugpolicy.ca\/#\/schema\/logo\/image\/","url":"https:\/\/drugpolicy.ca\/wp-content\/uploads\/2019\/04\/CDPC-logo-white-on-red-150-dpi.jpg","contentUrl":"https:\/\/drugpolicy.ca\/wp-content\/uploads\/2019\/04\/CDPC-logo-white-on-red-150-dpi.jpg","width":332,"height":333,"caption":"Canadian Drug Policy Coalition"},"image":{"@id":"https:\/\/mail.canadiandrugpolicy.ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mail.canadiandrugpolicy.ca\/#\/schema\/person\/c32110f234bdb1f5d978710b6b406a30","name":"Canadian Drug Policy Coalition","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f79e2b1a0ccc3ac68e2c3b14806186aa5e053de86cb3e0ee34e1971e8c4a3f7?s=96&d=mm&r=g","caption":"Canadian Drug Policy Coalition"},"description":"Advocating for public health- and human rights-based drug policy grounded in evidence, compassion, and social justice","url":"https:\/\/www.drugpolicy.ca\/fr\/author\/canadian-drug-policy-coalition\/"}]}},"mfb_rest_fields":["title","yoast_head","yoast_head_json"],"_links":{"self":[{"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/posts\/13326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/comments?post=13326"}],"version-history":[{"count":27,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/posts\/13326\/revisions"}],"predecessor-version":[{"id":13357,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/posts\/13326\/revisions\/13357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/media\/7983"}],"wp:attachment":[{"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/media?parent=13326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/categories?post=13326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.drugpolicy.ca\/fr\/wp-json\/wp\/v2\/tags?post=13326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}